{"id":58870,"date":"2024-11-25T00:00:00","date_gmt":"2024-11-24T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/entrainement-du-bas-du-corps-de-30-minutes\/"},"modified":"2024-11-25T00:00:00","modified_gmt":"2024-11-24T23:00:00","slug":"entrainement-du-bas-du-corps-de-30-minutes","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/bouge\/entrainement-du-bas-du-corps-de-30-minutes\/","title":{"rendered":"Entra\u00eenement de la semaine : Entra\u00eenement du bas du corps de 30 minutes"},"content":{"rendered":"\n<p><strong>TOUS LES NIVEAUX <\/strong>&nbsp;\/ entra\u00eenement du bas du corps \/ 30 minutes<\/p>\n\n\n\n<p><strong>\u00c9quipement<\/strong>&nbsp;: Barre, halt\u00e8res, machine hack squat et machine extension des jambes<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Certains redoutent le jour des jambes, d&#8217;autres l&#8217;adorent, mais personne n&#8217;y est indiff\u00e9rent. Les entra\u00eenements du bas du corps offrent de nombreux avantages, am\u00e9liorant la force accrue, la stabilit\u00e9 et ainsi les performances athl\u00e9tiques de mani\u00e8re globale. Cependant, un avantage est souvent n\u00e9glig\u00e9 : ils br\u00fblent plus de calories que les autres entra\u00eenements. C&#8217;est en grande partie parce que la plupart des exercices pour les jambes n\u00e9cessitent d\u2019engager tout le corps, ce qui entra\u00eene une d\u00e9pense calorique plus \u00e9lev\u00e9e.<\/p>\n\n\n\n<p>Tu peux profiter de tous ces avantages avec cet entra\u00eenement du bas du corps de 30 minutes. Il comprend 5 exercices, chacun compos\u00e9 de 12 r\u00e9p\u00e9titions. Tu effectueras 3 tours, en te reposant 1 minute entre chaque tour et exercice. Au total, cette s\u00e9ance d&#8217;entra\u00eenement devrait vous prendre environ 30 minutes.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Deadlift<\/li>\n\n\n\n<li>Dumbbell lunges<\/li>\n\n\n\n<li>Hack Squat<\/li>\n\n\n\n<li>Extensions des jambes<\/li>\n\n\n\n<li>Squat to calves raise<\/li>\n<\/ol>\n\n\n\n<p><strong>Faisons cette journ\u00e9e de jambe !<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/trial.evofitness.eu\/ch\/?lang=fr&amp;utm_source=website&amp;utm_medium=blog-banner&amp;utm_campaign=trial\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png\" alt=\"evo at trial cta 1day blog male fr\" class=\"wp-image-114632\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-960x422.png 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-768x338.png 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-480x211.png 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-640x281.png 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">MISE EN PLACE DE L&#8217;ENTRA\u00ceNEMENT<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>3 tours<\/li>\n\n\n\n<li>5 exercices<\/li>\n\n\n\n<li>12 r\u00e9p\u00e9titions<\/li>\n\n\n\n<li>1 minute de repos entre les exercices et les tours<\/li>\n\n\n\n<li>30 minutes<\/li>\n<\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">LISTE DES EXERCICES DE L&#8217;ENTRA\u00ceNEMENT<\/h2>\n\n\n\n<p><strong>3 tours<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">1 &#8211; DEADLIFT<\/h3>\n\n\n\n<p><strong>12 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mets-toi debout, pieds sous la barre, \u00e0 la largeur des hanches. La barre devrait \u00eatre juste au-dessus de tes pieds.<\/li>\n\n\n\n<li>Penche-toi et saisis la barre \u00e0 la largeur des \u00e9paules.<\/li>\n\n\n\n<li>Tout en gardant ton dos et tes bras droits, redresse-toi en tirant la barre le long de tes jambes, en utilisant la force de tes jambes.<\/li>\n\n\n\n<li>En haut du mouvement, contracte tes fessiers, ram\u00e8ne tes \u00e9paules en arri\u00e8re et expire.<\/li>\n\n\n\n<li>Pour redescendre la barre, repousse tes fesses en arri\u00e8re et baisse la barre devant tes jambes en gardant le dos droit.<\/li>\n\n\n\n<li>Plie les genoux une fois que la barre d\u00e9passe tes genoux et pose-la au sol.<\/li>\n\n\n\n<li>Garde ton corps droit et align\u00e9, tes bras tendus. \u00c9vite de cambrer exag\u00e9r\u00e9ment en haut du mouvement.<\/li>\n\n\n\n<li>Reste proche de la barre pour optimiser la m\u00e9canique du mouvement.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/r0GMHPAjMqY?si=p0UJfuXq2ScD2yBb\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; DUMBBELL LUNGES<\/h3>\n\n\n\n<p><strong>12 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mets-toi debout, halt\u00e8res aux \u00e9paules.<\/li>\n\n\n\n<li>Avance la jambe droite en gardant le talon bien au sol.<\/li>\n\n\n\n<li>L\u00e8ve l\u00e9g\u00e8rement le talon de la jambe arri\u00e8re.<\/li>\n\n\n\n<li>Fl\u00e9chis ensuite les deux genoux jusqu&#8217;\u00e0 ce que le genou arri\u00e8re fr\u00f4le le sol, assure-toi que ta hanche et ton genou sont bien align\u00e9s.<\/li>\n\n\n\n<li>Recommence le mouvement pour le nombre de r\u00e9p\u00e9titions n\u00e9cessaires.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/2EN15_qm-Ls?si=R2DlWW38C4BvXHQw\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; HACK SQUAT<\/h3>\n\n\n\n<p><strong>12 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mets-toi debout sur la machine avec les coussins reposant sur tes \u00e9paules.<\/li>\n\n\n\n<li>Positionne tes pieds comme pour un squat classique.<\/li>\n\n\n\n<li>Active ton tronc pour sentir la pression du coussin contre ton corps.<\/li>\n\n\n\n<li>Cette machine est id\u00e9ale pour t\u2019aider \u00e0 r\u00e9aliser des squats profonds.<\/li>\n\n\n\n<li>Descends lentement jusqu&#8217;\u00e0 ressentir une perte de stabilit\u00e9 du tronc ou jusqu&#8217;\u00e0 ce que ton bassin perde le contact avec le coussin.<\/li>\n\n\n\n<li>R\u00e9p\u00e8te l&#8217;exercice.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/XpYQIsa4K0s?si=lKSatLFBlnfw2ypS\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; EXTENSIONS DE JAMBES<\/h3>\n\n\n\n<p><strong>12 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Assieds-toi droit sur la machine.<\/li>\n\n\n\n<li>Ajuste le coussin pour qu\u2019il repose juste au-dessus de tes pieds, sur le bas de ta jambe.<\/li>\n\n\n\n<li>\u00c9tends tes jambes devant toi, en utilisant bien tes quadriceps pour g\u00e9n\u00e9rer le mouvement.<\/li>\n\n\n\n<li>Ram\u00e8ne lentement tes jambes \u00e0 la position de d\u00e9part.<\/li>\n\n\n\n<li>R\u00e9p\u00e8te le mouvement.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/l0lmzG4mQ8U?si=8maE8E4GrcVtRnsc\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">5 &#8211; SQUATS TO CALVE RAISES<\/h3>\n\n\n\n<p><strong>12 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mets-toi debout, les pieds un peu plus larges que tes \u00e9paules, les orteils l\u00e9g\u00e8rement tourn\u00e9s vers l&#8217;ext\u00e9rieur.<\/li>\n\n\n\n<li>Tends tes bras devant toi pour t\u2019aider \u00e0 garder l&#8217;\u00e9quilibre.<\/li>\n\n\n\n<li>Accroupis-toi jusqu&#8217;\u00e0 ce que le haut de tes jambes soit presque parall\u00e8le au sol.<\/li>\n\n\n\n<li>L\u00e8ve-toi de mani\u00e8re explosive, en te propulsant sur la pointe des pieds \u00e0 la fin du mouvement pour ajouter de l&#8217;intensit\u00e9.<\/li>\n\n\n\n<li>Utilise tes bras pour gagner en dynamisme et \u00e9lan.<\/li>\n\n\n\n<li>R\u00e9p\u00e8te l&#8217;exercice.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/XZ7uriUfiRU?si=mBs0mshiUOVY6Ajf\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Entra\u00eenement du bas du corps : termin\u00e9. D\u00e9couvre ton prochain d\u00e9fi ci-dessous :<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-metabolique-de-20minutes\/\">Entra\u00eenement de force m\u00e9tabolique de 20 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-au-poids-du-corps-50-40-30-20-10\/\">Entra\u00eenement au poids du corps 50-40-30-20-10<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-amrap-du-haut-du-corp-de-12-minutes\/\">Entra\u00eenement AMRAP du haut du corps de 12&nbsp;minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-metabolique-de-15minutes\/\">Entra\u00eenement de force m\u00e9tabolique de 15&nbsp;min<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-et-de-conditionnement-du-bas-du-corps-du-12-minutes\/\">Entra\u00eenement de force et de conditionnement du bas du corps de 12 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-cardio-en-zone-2-de-30-minutes\/\">Entra\u00eenement cardio de 30&nbsp;min en zone 2<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-du-bas-du-corps-de-15minutes\/\">Entra\u00eenement de force du bas du corps de 15 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-emom-de-20minutes\/\">Entra\u00eenement de force EMOM de 20&nbsp;minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-pour-le-haut-du-corps-de-30-minutes\/\">Entra\u00eenement de force du haut du corps de 30 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-complet-du-corps-de-35minutes\/\">Entra\u00eenement de force complet du corps de 35 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-pour-le-dos-et-les-epaules-de-16-minutes\/\">Entra\u00eenement pour le dos et les \u00e9paules de 16 minutes<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img decoding=\"async\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_fr.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105050\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>TOUS LES NIVEAUX &nbsp;\/ entra\u00eenement du bas du corps \/ 30 minutes \u00c9quipement&nbsp;: Barre, halt\u00e8res, machine hack squat et machine&#8230;<\/p>\n","protected":false},"author":26,"featured_media":58868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Entra\u00eenement du bas du corps de 30 minutes | EVO Fitness","_seopress_titles_desc":"On peut les d\u00e9tester au les adorer, les exercices pour le jour des jambes est essentiel. D\u00e9couvre cet entra\u00eenement du bas du corps de 30 minutes.","_seopress_robots_index":"","_seopress_analysis_target_kw":"entra\u00eenement du bas du corps","footnotes":""},"categories":[1690],"tags":[1664,2326,2396,2538],"class_list":["post-58870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bouge","tag-entrainement","tag-entrainement-de-la-semaine","tag-edls","tag-entrainement-du-bas-du-corps"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/58870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=58870"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/58870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/58868"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=58870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=58870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=58870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}