{"id":58787,"date":"2024-08-12T00:00:00","date_gmt":"2024-08-11T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/entrainement-fonctionnel-au-poids-du-corps-de-20-minutes\/"},"modified":"2024-08-12T00:00:00","modified_gmt":"2024-08-11T22:00:00","slug":"entrainement-fonctionnel-au-poids-du-corps-de-20-minutes","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/bouge\/entrainement-fonctionnel-au-poids-du-corps-de-20-minutes\/","title":{"rendered":"Entra\u00eenement de la semaine\u00a0: Entra\u00eenement fonctionnel au poids du corps de 20\u00a0minutes"},"content":{"rendered":"\n<p><strong>TOUS LES NIVEAUX&nbsp;<\/strong>\/ entra\u00eenement fonctionnel au poids du corps \/ 20 minutes<\/p>\n\n\n\n<p><strong>\u00c9quipement <\/strong>: Tapis d\u2019exercice<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>L\u2019\u00e9t\u00e9 est la p\u00e9riode id\u00e9ale pour des entra\u00eenements simples et sans \u00e9quipement, que tu peux faire n\u2019importe o\u00f9.<\/strong> Alors que les temp\u00e9ratures augmentent et que les vacances d&#8217;\u00e9t\u00e9 commencent, il est tentant de trouver toutes sortes d&#8217;excuses pour ne pas faire d&#8217;exercice, mais pas avec cet <strong>entra\u00eenement fonctionnel au poids du corps<\/strong>.<\/p>\n\n\n\n<p>Compos\u00e9 de <strong>4 exercices<\/strong>, tu devras effectuer <strong>10 tours suivant cet ordre particulier de r\u00e9p\u00e9titions&nbsp;: 20-18-16-14-12-10-8-6-4-2. <\/strong>En gros, au premier tour, il faut faire <strong>20 r\u00e9p\u00e9titions de chaque exercice, et tu auras alors 2 r\u00e9p\u00e9titions de moins \u00e0 chaque tour<\/strong>.&nbsp;Pour un d\u00e9fi suppl\u00e9mentaire, <strong>l&#8217;id\u00e9e est de r\u00e9aliser cette s\u00e9ance en seulement 20 minutes<\/strong>.<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Burpees<\/li>\n\n\n\n<li>Squats<\/li>\n\n\n\n<li>Pompes<\/li>\n\n\n\n<li>Single-leg tuck-ups<\/li>\n<\/ol>\n\n\n\n<p><strong>Allons-y !<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img decoding=\"async\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_fr.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105050\"\/><\/a><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">MISE EN PLACE DE L&#8217;ENTRA\u00ceNEMENT<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>4 exercices<\/li>\n\n\n\n<li>20 r\u00e9p\u00e9titions de chaque exercice au 1er tour<\/li>\n\n\n\n<li>2 r\u00e9p\u00e9titions de moins \u00e0 chaque tour suivant<\/li>\n\n\n\n<li>10 tours au total<\/li>\n\n\n\n<li>Pas de repos entre les exercices et les tours<\/li>\n\n\n\n<li>20 minutes<\/li>\n\n\n\n<li>\u00c9quipement : Tapis d\u2019exercice<\/li>\n<\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">LISTE DES EXERCICES DE L&#8217;ENTRA\u00ceNEMENT<\/h2>\n\n\n\n<p><strong>10 tours<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">1 \u2013 Burpees<\/h3>\n\n\n\n<p><strong>20, 18, 16, 14, 12, 10, 8, 6, 4, 2 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Debout, engage ton tronc.<\/li>\n\n\n\n<li>Plie-toi rapidement pour toucher le sol devant tes pieds et saute, en projetant tes jambes en arri\u00e8re, pour atterrir en position de pompe.<\/li>\n\n\n\n<li>Fais une pompe, puis en remontant, projette tes hanches vers le haut et saute en position accroupie.<\/li>\n\n\n\n<li>Remets-toi debout et recommence le mouvement.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/HriWU1sMnVc?si=klQNQH0vVtZUbw9I\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div> \n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; Squats<\/h3>\n\n\n\n<p><strong>20, 18, 16, 14, 12, 10, 8, 6, 4, 2 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Place-toi debout, les pieds \u00e0 la largeur de tes \u00e9paules.<\/li>\n\n\n\n<li>Engage ton tronc et commence \u00e0 te baisser tout en gardant tes genoux align\u00e9s avec tes pieds. Garde tes abdominaux et tes fessiers contract\u00e9s pour stabiliser tes hanches.<\/li>\n\n\n\n<li>Utilise tes bras pour maintenir l\u2019\u00e9quilibre tout au long du mouvement.<\/li>\n\n\n\n<li>Assure-toi que tes pieds restent bien plats au sol et descends en squat aussi bas que possible sans soulever tes talons ou ressentir de douleur au bas du dos.<\/li>\n\n\n\n<li>R\u00e9p\u00e8te le mouvement.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/mUR7dPOtuG8?si=zK-mIPOSPvfWRWCT\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>  \n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; Pompes<\/h3>\n\n\n\n<p><strong>20, 18, 16, 14, 12, 10, 8, 6, 4, 2 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Place-toi en position de planche, bras tendus, avec les \u00e9paules directement au-dessus de tes poignets, et garde ton corps bien droit.<\/li>\n\n\n\n<li>Contracte fermement ton tronc et tes fessiers pour stabiliser ta position.<\/li>\n\n\n\n<li>En maintenant cette tension, descends tout ton corps vers le sol en contr\u00f4lant le mouvement jusqu&#8217;\u00e0 ce que tu sois le plus bas possible sans te coucher.<\/li>\n\n\n\n<li>Pousse ensuite fermement contre le sol pour remonter \u00e0 la position initiale.<\/li>\n\n\n\n<li>R\u00e9p\u00e8te ce mouvement.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/77sU-59dRUs?si=DRADihDauL-aul1C\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>  \n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; Single-leg tuck-ups<\/h3>\n\n\n\n<p><strong>20, 18, 16, 14, 12, 10, 8, 6, 4, 2 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Allonge-toi sur le dos, les jambes tendues et les bras \u00e0 tes c\u00f4t\u00e9s.<\/li>\n\n\n\n<li>Penche-toi l\u00e9g\u00e8rement en avant et rapproche un genou vers ta poitrine.<\/li>\n\n\n\n<li>Garde le pied oppos\u00e9 droit et pos\u00e9 sur le sol.<\/li>\n\n\n\n<li>Approche tes mains vers le genou relev\u00e9.<\/li>\n\n\n\n<li>R\u00e9p\u00e8te ce mouvement.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/6lJ-LQ-yQ3s?si=ROvwiTFLLPyQsEja\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div> \n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">H4&nbsp;: Si tu as aim\u00e9 cet entra\u00eenement fonctionnel au poids du corps, tu vas adorer les entra\u00eenements que nous avons pour toi ci-dessous&nbsp;:<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-metabolique-de-12-minutes\/\">Entra\u00eenement de force m\u00e9tabolique de 12 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-emom-de-30-minutes\/\">Entra\u00eenement de force EMOM de 30 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-poitrine-et-triceps-de-35-minutes\/\">Entra\u00eenement poitrine et triceps de 35 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-complet-du-corps-chronometre\/\">Entra\u00eenement complet du corps chronom\u00e9tr\u00e9<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-pyramidal-complet-de-20-minutes\/\">Entra\u00eenement pyramidal complet de 20 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-au-poids-du-corps-complet-de-30-minutes\/\">Entra\u00eenement au poids du corps complet de 30 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-complet-de-18-minutes\/\">Entra\u00eenement de force complet de 18 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-complet-du-corps-de-25-minutes\/\">Entra\u00eenement de force complet du corps de 25 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-des-fessiers-de-20-minutes\/\">Entra\u00eenement des fessiers de 20 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-100-repetitions-en-30-minutes\/\">Entra\u00eenement de 100 r\u00e9p\u00e9titions en 30 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-de-force-emom-de-21-minutes\/\">Entra\u00eenement de force EMOM de 21 minutes<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-poitrine-et-triceps-de-20-minutes\/\">Entra\u00eenement de la semaine : Entra\u00eenement poitrine et triceps de 20 minutes<\/a><\/li>\n<\/ul>\n\n\n","protected":false},"excerpt":{"rendered":"<p>TOUS LES NIVEAUX&nbsp;\/ entra\u00eenement fonctionnel au poids du corps \/ 20 minutes \u00c9quipement : Tapis d\u2019exercice L\u2019\u00e9t\u00e9 est la p\u00e9riode&#8230;<\/p>\n","protected":false},"author":26,"featured_media":58785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Entra\u00eenement fonctionnel au poids du corps de 20\u00a0minutes | EVO Fitness","_seopress_titles_desc":"L\u2019\u00e9t\u00e9 est parfait pour s\u2019entra\u00eener sans \u00e9quipement, n\u2019importe o\u00f9. C&#039;est pourquoi nous te proposons cet entra\u00eenement fonctionnel au poids du corps.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Entra\u00eenement fonctionnel au poids du corps","footnotes":""},"categories":[1690],"tags":[1664,2326,2396,2426,2620,2708],"class_list":["post-58787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bouge","tag-entrainement","tag-entrainement-de-la-semaine","tag-edls","tag-poids-du-corps","tag-entrainement-fonctionnel-au-poids-du-corps","tag-bodyweight-3"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/58787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=58787"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/58787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/58785"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=58787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=58787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=58787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}