{"id":57856,"date":"2021-01-18T00:00:00","date_gmt":"2021-01-17T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/entrainement-fonctionnel-de-30-minutes\/"},"modified":"2021-01-18T00:00:00","modified_gmt":"2021-01-17T23:00:00","slug":"entrainement-fonctionnel-de-30-minutes","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/bouge\/entrainement-fonctionnel-de-30-minutes\/","title":{"rendered":"Entra\u00eenement de la semaine : entra\u00eenement fonctionnel de 30 minutes poir am\u00e9liorer la force"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ENTRA\u00ceNEMENT FONCTIONNEL DE 30 MINUTES POIR AM\u00c9LIORER LA FORCE<\/strong><\/h2>\n\n\n\n<p><strong>TOUS LES NIVEAUX \/ <\/strong>entra\u00eenement fonctionnel pour am\u00e9liorer la force \/ 30 minutes<\/p>\n\n\n\n<p><strong>Equiepment <\/strong>: Halt\u00e8res, kettlebell et tapis de gym.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Trouver la force int\u00e9rieure pour faire de l&#8217;exercice n&#8217;est pas toujours simple. Certaines personnes pr\u00e9f\u00e8rent <a href=\"https:\/\/evofitness.ch\/fr\/sentrainer-le-matin\/\">s&#8217;entra\u00eener le matin<\/a>, d&#8217;autres l&#8217;apr\u00e8s-midi. Certains se sentent mis au d\u00e9fi de s&#8217;entra\u00eener avec quelqu&#8217;un, et d&#8217;autres pr\u00e9f\u00e8rent s&#8217;entra\u00eener seuls.<\/p>\n\n\n\n<p><strong>Tout cela pour dire que nous sommes tous diff\u00e9rents<\/strong>. Et nous trouvons tous des moyens de g\u00e9rer ces jours o\u00f9 nous avons envie de ne pas nous entra\u00eener du tout. Mais <strong>nous faisons ce qui doit \u00eatre fait.<\/strong><\/p>\n\n\n\n<p>Cet entra\u00eenement enti\u00e8rement fonctionnel est un excellent moyen de vous faire garder la forme. Il s&#8217;agit d&#8217;une v\u00e9ritable s\u00e9ance d&#8217;entra\u00eenement mettant l&#8217;accent sur la force, pr\u00e9par\u00e9e par <strong>Jakob Ritter, notre entra\u00eeneur personnel de <a href=\"https:\/\/evofitness.at\/en\/evo-fitness-vienna-mariahilferstrasse\/\">l&#8217;EVO Mariahilfer Stra\u00dfe<\/a> \u00e0 Vienne<\/strong>.<\/p>\n\n\n\n<p>Voici 5 exercices que vous devez effectuer sur 3 tours :<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Curl et presse \u00e9paules<\/li><li>Combinaison pompes\/rameur<\/li><li>Torsion du tronc kettlebell\/halt\u00e8re<\/li><li>Kettlebell deadlift<\/li><li>Combo squat et \u00e9tirement des mollets<\/li><\/ol>\n\n\n\n<p>Le nombre de r\u00e9p\u00e9titions changera d&#8217;un exercice \u00e0 l&#8217;autre, et vous pouvez les ajuster en fonction de votre niveau de forme physique. Si c&#8217;est la premi\u00e8re fois que vous effectuez un entra\u00eenement fonctionnel, concentrez-vous sur le perfectionnement de vos mouvements et moins sur la vitesse \u00e0 laquelle vous pouvez les terminer.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">ENTRA\u00ceNEMENT FONCTIONNEL DE 30 MINUTES<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1 \u2013 CURL ET PRESSE \u00c9PAULES<\/h3>\n\n\n\n<p><strong>12 \u2013 15 rep\u00e9titions , 3 tous<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Prenez deux halt\u00e8res avec un poids ad\u00e9quat pour votre niveau de forme physique.<\/li><li>Tenez-vous droit, posez les halt\u00e8res sur les c\u00f4t\u00e9s avec les paumes tourn\u00e9es vers l&#8217;int\u00e9rieur.<\/li><li>Soulevez lentement vos avant-bras vers l&#8217;avant jusqu&#8217;\u00e0 ce que votre poignet repose au-dessus de votre coude.<\/li><li>Maintenant, fixez vos bras fortement et soulevez les halt\u00e8res au-dessus de votre t\u00eate.<\/li><li>Maintenez cette position pendant une seconde et revenez au point de d\u00e9part en inversant le mouvement.<\/li><li>R\u00e9p\u00e9tez.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/rWVrl-ULZdE\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 \u2013 COMBINAISON POMPES\/RAMEUR<\/h3>\n\n\n\n<p><strong>8 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9, 3 tours<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Prenez un halt\u00e8re l\u00e9ger et pr\u00e9parez votre corps.<\/li><li>Vos mains et vos pieds doivent \u00eatre plus \u00e9cart\u00e9s que la largeur des \u00e9paules.<\/li><li>Abaissez maintenant votre corps jusqu&#8217;\u00e0 ce que votre poitrine soit parall\u00e8le \u00e0 vos mains.<\/li><li>Poussez avec puissance et commencez \u00e0 ramer un halt\u00e8re jusqu&#8217;\u00e0 votre poitrine.<\/li><li>Revenez lentement \u00e0 la position de d\u00e9part jusqu&#8217;\u00e0 ce que vous ayez atteint le nombre de r\u00e9p\u00e9titions souhait\u00e9.<\/li><\/ul>\n\n\n\n<p><strong>Petit conseil de Jakob : <\/strong>gardez votre corps bien contract\u00e9 pendant tout le mouvement.<\/p>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/K3jf1fL-sGw\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/6v9dXUAdA5k\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 \u2013 TORSION DU TRONC KETTLEBELL\/HALT\u00c8RE<\/h3>\n\n\n\n<p><strong>10 rep\u00e9titions de chaque c\u00f4t\u00e9, 3 tours<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Trouvez un sol mou, de pr\u00e9f\u00e9rence un tapis de gym et prenez un kettlebell ou un halt\u00e8re avec un poids ad\u00e9quat.<\/li><li>Placez vos fessiers sur le sol et soulevez vos pieds en l&#8217;air.<\/li><li>Saisissez maintenant la kettlebell comme indiqu\u00e9 sur l&#8217;vid\u00e9o ci-dessous.<\/li><li>Commencez lentement \u00e0 tordre le kettlebell jusqu&#8217;\u00e0 ce que vous sentiez un l\u00e9ger \u00e9tirement du c\u00f4t\u00e9 oppos\u00e9 du tronc.<\/li><li>Maintenez la position pendant une br\u00e8ve seconde et tournez-vous de l&#8217;autre c\u00f4t\u00e9.<\/li><li>R\u00e9p\u00e9tez pour le nombre de r\u00e9p\u00e9titions souhait\u00e9.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/OIMhc44zQB4\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; KETTLEBELL DEADLIFT<\/h3>\n\n\n\n<p><strong>12 r\u00e9p\u00e9titions, 3 tours<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Prenez une kettlebell et placez-la entre vos pieds qui doivent \u00eatre \u00e0 la largeur des \u00e9paules.<\/li><li>Pliez l\u00e9g\u00e8rement les genoux, pliez le haut du corps vers l&#8217;avant et saisissez la poign\u00e9e.<\/li><li>Maintenant, tendez votre tronc et tout en gardant le dos droit, soulevez le kettlebell jusqu&#8217;au niveau des hanches.<\/li><li>Au sommet, vous devez \u00eatre bien et garder les \u00e9paules, le tronc et les fessiers bien contract\u00e9s.<\/li><li>Redescendez maintenant lentement tout en gardant votre corps bien contract\u00e9.<\/li><li>R\u00e9p\u00e9tez pour le nombre de r\u00e9p\u00e9titions souhait\u00e9.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ISy5vAdvaa0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">5 \u2013 COMBO SQUAT ET \u00c9TIREMENT DES MOLLETS<\/h3>\n\n\n\n<p><strong>12 \u00e0 15 r\u00e9p\u00e9titions, 3 tours<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>En vous tenant droit, placez vos pieds l\u00e9g\u00e8rement plus loin que la largeur des \u00e9paules, les orteils point\u00e9s vers l&#8217;ext\u00e9rieur.<\/li><li>\u00c9tendez vos bras devant votre corps.<\/li><li>Maintenant accroupissez-vous jusqu&#8217;\u00e0 ce que le haut de votre jambe soit \u00e0 peu pr\u00e8s parall\u00e8le au sol.<\/li><li>Soulevez-vous de mani\u00e8re intense et terminez l&#8217;exercice en vous mettant debout sur vos orteils lorsque vous revenez au sommet.<\/li><li>Pour am\u00e9liorer encore davantage l&#8217;intensit\u00e9, vous pouvez utiliser vos bras pour un peu d&#8217;\u00e9lan.<\/li><li>R\u00e9p\u00e9tez pour le nombre de r\u00e9p\u00e9titions souhait\u00e9.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/7tErhBAhHY0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>R\u00e9p\u00e9tez tous ces exercices sur 3 tours.<\/strong><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Voici un entra\u00eenement fonctionnel amusant et id\u00e9al pour rester en forme. Voici quelques autres entra\u00eenements de la semaine que vous pouvez essayer:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-pilates-de-30-minutes\/\">Entra\u00eenement pilates de 30 minutes pour am\u00e9liorer la force et la puissance<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/entraintment-hiit-de-30-minutes\/\">Entra\u00eentment HIIT complet du corps de 30 minutes<\/a><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img decoding=\"async\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_fr.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105050\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ENTRA\u00ceNEMENT FONCTIONNEL DE 30 MINUTES POIR AM\u00c9LIORER LA FORCE TOUS LES NIVEAUX \/ entra\u00eenement fonctionnel pour am\u00e9liorer la force \/&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Entra\u00eenement fonctionnel de 30 minutes pour la force | EVO Fitness","_seopress_titles_desc":"Cette semaine, nous vous proposons une s\u00e9ance d&#039;entra\u00eenement fonctionnel \u00e0 l&#039;aide de notre entra\u00eeneur personnel Jakob Ritter.","_seopress_robots_index":"","_seopress_analysis_target_kw":"entra\u00eenement fonctionnel","footnotes":""},"categories":[1690],"tags":[1664,1702,2074,2326,2901],"class_list":["post-57856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bouge","tag-entrainement","tag-entrainement-fonctionnel","tag-fonctionnel","tag-entrainement-de-la-semaine","tag-wow-3"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57856"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57855"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}