{"id":57849,"date":"2021-01-07T00:00:00","date_gmt":"2021-01-06T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/entrainement-pilates-de-30-minutes\/"},"modified":"2021-01-07T00:00:00","modified_gmt":"2021-01-06T23:00:00","slug":"entrainement-pilates-de-30-minutes","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/bouge\/entrainement-pilates-de-30-minutes\/","title":{"rendered":"Entra\u00eenement de la semaine : entra\u00eenement pilates de 30 minutes pour am\u00e9liorer la force et la puissance"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ENTRA\u00ceNEMENT PILATES DE 30 MINUTES POUR AM\u00c9LIORER LA FORCE ET LA PUISSANCE<\/strong><\/h2>\n\n\n\n<p><strong><strong>TOUS LES NIVEAUX<\/strong> <\/strong>\/ entra\u00eenement pilates \/ force et puissance \/ 30 minutes<\/p>\n\n\n\n<p><strong>Equipement : <\/strong>Halt\u00e8re et tapis de gym.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Comme promis lundi dernier, \u00e0 chaque nouvelle semaine, nous aurons une nouvelle s\u00e9ance d&#8217;entra\u00eenement. Cette fois, nous comptons sur <strong>Carolina L\u00fcthi, notre entra\u00eeneur personnel du club <a href=\"https:\/\/evofitness.ch\/fr\/evo-zurich-enge\/\">EVO Zurich Enge<\/a><\/strong>, pour vous proposer un entra\u00eenement pilates pour am\u00e9liorer la puissance et la force.<\/p>\n\n\n\n<p>Le Pilates est <a href=\"https:\/\/www.pilatesfoundation.com\/pilates\/the-history-of-pilates\/\">une m\u00e9thode de fitness r\u00e9cente<\/a>, elle remonte au d\u00e9but du 20e si\u00e8cle, empruntant son nom \u00e0 son cr\u00e9ateur Joseph Pilates. Joseph estime que \u00ab le changement passe par le mouvement et que le mouvement gu\u00e9rit \u00bb, ce qui est tr\u00e8s \u00e9troitement align\u00e9 sur <a href=\"https:\/\/evofitness.ch\/fr\/training-philosophy\/\">la philosophie d&#8217;EVO<\/a>.<\/p>\n\n\n\n<p>Nous sommes de grands fans du <strong>mouvement en tant que principe cl\u00e9 de nos entra\u00eenements<\/strong>, le consid\u00e9rant non pas comme une intervention, mais comme un \u00e9l\u00e9ment naturel. C\u2019est ce que nous tenterons d\u2019obtenir avec cet entra\u00eenement.<\/p>\n\n\n\n<p>Cet entra\u00eenement pilates se compose de 5 exercices qui seront effectu\u00e9s en 3 tours, diminuant le nombre de r\u00e9p\u00e9titions \u00e0 chaque tour.<\/p>\n\n\n\n<p><strong>Tour 1<\/strong>:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>El\u00e9vation de la poitrine avec rotation \u2013 20x de chaque c\u00f4t\u00e9 en gardant les \u00e9paules \u00e9loign\u00e9es du sol<\/li><li>Courbure lat\u00e9rale \u2013 20x sur le c\u00f4t\u00e9 droit; 20x sur le c\u00f4t\u00e9 gauche<\/li><li>Double leg kick \u2013 20x<\/li><li>Standing roll down &#8211; 10x<\/li><li>Fente et rotation avec poids &#8211; 20x vers le c\u00f4t\u00e9 droit; 20x sur le c\u00f4t\u00e9 gauche.<\/li><\/ol>\n\n\n\n<p><strong>Tour 2<\/strong>: 15 r\u00e9p\u00e9titions de chaque exercice et 10 r\u00e9p\u00e9titions du Standing roll down<\/p>\n\n\n\n<p><strong>Tour 3<\/strong>: 10 r\u00e9p\u00e9titions de chaque<\/p>\n\n\n\n<p>Effectuez les exercices \u00e0 un rythme constant sans temps de repos entre chaque exercice ni apr\u00e8s chaque tour.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">ENTRA\u00ceNEMENT PILATES DE 30 MINUTES<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1 \u2013 El\u00e9vation de la poitrine avec rotation<\/h3>\n\n\n\n<p><strong>1er tour : 20 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<br>2\u00e8me tour : 15 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<br>3\u00e8me tour : 10 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<\/strong><\/p>\n\n\n\n<p><strong>Comment r\u00e9aliser cet exercice :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>&nbsp;Inspirez et expirez pour vous mettre en position.<\/li><li>&nbsp;Expirez et tournez \u00e0 droite en regardant par-dessus vos genoux.<\/li><li>Inspirez \u00e0 nouveau et r\u00e9p\u00e9tez du c\u00f4t\u00e9 gauche.<\/li><li>N&#8217;oubliez pas de bouger la t\u00eate, les \u00e9paules et la poitrine ensemble et de garder votre bassin stable.<\/li><li>Vous pouvez augmenter la difficult\u00e9 en soulevant vos genoux.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/vBCgJ9VWyMo\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 \u2013 Courbure lat\u00e9rale<\/h3>\n\n\n\n<p><strong>1er tour : 20 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<br>2\u00e8me tour : 15 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<br>3\u00e8me tour : 10 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<\/strong><\/p>\n\n\n\n<p><strong>Comment r\u00e9aliser cet exercice :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Allongez-vous sur le c\u00f4t\u00e9, pliez la jambe la plus proche du sol et gardez l&#8217;autre droite.<\/li><li>Appuyez sur votre coude et redressez votre corps pour soulever le bassin du tapis.<\/li><li>Visez une forme en arc-en-ciel pendant que vous tendez la main pour essayer d&#8217;aller le plus loin possible.<\/li><li>R\u00e9p\u00e9tez et changez de c\u00f4t\u00e9 apr\u00e8s avoir termin\u00e9 le nombre de r\u00e9p\u00e9titions.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/hDGCHcO51_M\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; Double leg kick<\/h3>\n\n\n\n<p><strong>1er tour : 20 r\u00e9p\u00e9titions<br>2\u00e8me tour : 15 r\u00e9p\u00e9titions<br>3\u00e8me tour : 10 r\u00e9p\u00e9titions<\/strong><\/p>\n\n\n\n<p><strong>Comment r\u00e9aliser cet exercice :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Serrez vos mains derri\u00e8re votre dos aussi haut que possible et laissez vos coudes tomber vers le sol.<\/li><li>Engagez votre tronc et soulevez votre abdomen du tapis.<\/li><li>Gardez vos jambes jointes, frappez vos talons vers les hanches: un coup de pied en trois parties avec une expiration en trois parties.<\/li><li>Gardez vos mains jointes et \u00e9tendez vos bras derri\u00e8re vous pendant que vous inspirez, en \u00e9tirant vos jambes au-dessus du tapis et votre t\u00eate aussi.<\/li><li>Expirez et revenez \u00e0 la position de d\u00e9part.<\/li><li>R\u00e9p\u00e9tez.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/E3wk8Q8_EjA\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; Standing roll down<\/h3>\n\n\n\n<p><strong>10 r\u00e9p\u00e9titions \u00e0 chaque tour<\/strong><\/p>\n\n\n\n<p><strong>Comment r\u00e9aliser cet exercice :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tenez-vous avec les hanches \u00e9cart\u00e9es.<\/li><li>Inspirez en abaissant votre menton vers votre poitrine.<\/li><li>Expirez et laissez vos \u00e9paules plier le haut de votre corps<\/li><li>Maintenant que vous \u00eates en positions de planche compl\u00e8te, effectuez une pompe (note : comme vous pouvez le voir dans la vid\u00e9o, il existe une variante plus simple : <a href=\"https:\/\/evofitness.ch\/fr\/pompes-sur-les-genoux\/\">la pompe sur les genoux<\/a>).<\/li><li>Expirez et tenez-vous lentement debout, en redressant les vert\u00e8bres, le dos puis la t\u00eate en dernier.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/mNai3SIg1KE\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">5 \u2013 Fente et rotation avec poids<\/h3>\n\n\n\n<p><strong>1er tour : 20 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<br>2\u00e8me tour : 15 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<br>3\u00e8me tour : 10 r\u00e9p\u00e9titions de chaque c\u00f4t\u00e9<\/strong><\/p>\n\n\n\n<p><strong>Comment r\u00e9aliser cet exercice :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tenez-vous debout, les pieds \u00e9cart\u00e9s de la largeur des \u00e9paules.<\/li><li>Tenez l&#8217;halt\u00e8re devant vous et avancez pour effectuer une fente classique, ne permettant pas \u00e0 votre genou de passer par-dessus votre jambe avant.<\/li><li>Tournez le haut de votre corps sur le c\u00f4t\u00e9 de la jambe avant, en gardant le tronc engag\u00e9 et en contractant vos fessiers.<\/li><li>En gardant le contr\u00f4le, ramenez les bras au milieu et ramenez votre pied.<\/li><li>R\u00e9p\u00e9tez.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/LnbXF-6-vFI\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Et voil\u00e0, une s\u00e9ance d&#8217;entra\u00eenement pilates qui vous fera vous sentir plus fort et plus r\u00e9sistant. Pendant que vous \u00eates ici, assurez-vous de consulter notre dernier entra\u00eenement de la semaine:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/evofitness.ch\/fr\/entraintment-hiit-de-30-minutes\/\">Entra\u00eentment HIIT complet du corps de 30 minutes<\/a><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/trial.evofitness.eu\/ch\/?lang=fr&amp;utm_source=website&amp;utm_medium=blog-banner&amp;utm_campaign=trial\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png\" alt=\"evo at trial cta 1day blog male fr\" class=\"wp-image-114632\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-960x422.png 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-768x338.png 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-480x211.png 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-640x281.png 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ENTRA\u00ceNEMENT PILATES DE 30 MINUTES POUR AM\u00c9LIORER LA FORCE ET LA PUISSANCE TOUS LES NIVEAUX \/ entra\u00eenement pilates \/ force&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Entra\u00eenement pilates de 30 minutes pour la force | EVO Fitness","_seopress_titles_desc":"Le pilates s&#039;aligne avec la philosophie d&#039;EVO. Voici un entra\u00eenement pilates de notre entra\u00eeneur personnel Carolina L\u00fcthi pour le prouver.","_seopress_robots_index":"","_seopress_analysis_target_kw":"entra\u00eenement pilates","footnotes":""},"categories":[1690],"tags":[1664,2326,2328,2901,2905],"class_list":["post-57849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bouge","tag-entrainement","tag-entrainement-de-la-semaine","tag-entrainement-pilates","tag-wow-3","tag-pilates-3"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57849"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57847"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}