{"id":57782,"date":"2022-11-16T00:00:00","date_gmt":"2022-11-15T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/exercices-anti-rotation\/"},"modified":"2022-11-16T00:00:00","modified_gmt":"2022-11-15T23:00:00","slug":"exercices-anti-rotation","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/bouge\/exercices-anti-rotation\/","title":{"rendered":"4 exercices anti-rotation \u00e0 inclure \u00e0 votre entra\u00eenement"},"content":{"rendered":"\n<p>Vous vous posez des questions sur votre programme d\u2019entra\u00eenement et si vous r\u00e9pondez aux besoins de chaque muscle ?<\/p>\n\n\n\n<p>Vous pouvez voir que vous avez d\u00e9velopp\u00e9 vos muscles, votre force, votre agilit\u00e9, mais <strong>vous vous demandez toujours quels domaines vous pourriez am\u00e9liorer ?<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">D\u00e9couvrez les exercices anti-rotation.<\/h3>\n\n\n\n<p><strong>Cette m\u00e9thode d\u2019entra\u00eenement utilise la capacit\u00e9 du corps \u00e0 emp\u00eacher la rotation et \u00e0 r\u00e9sister \u00e0 certains mouvements \/ positions, tout en favorisant la stabilit\u00e9 et l\u2019alignement de votre corps.<\/strong> Ces exercices vous aident \u00e0 <strong>renforcer votre stabilit\u00e9 et votre force<\/strong>. <\/p>\n\n\n\n<p>Quotidiennement, <strong>vous soumettez votre corps \u00e0 diff\u00e9rents types de d\u00e9fis<\/strong>. Vous portez vos sacs de course et vous pouvez parfois vous sentir d\u00e9s\u00e9quilibr\u00e9 en tr\u00e9buchant sur un trottoir, en marchant sur une route verglac\u00e9e ou en percutant quelqu\u2019un ou quelque chose. Comme leur nom l&#8217;indique, les exercices anti-rotation peuvent vous aider \u00e0 d\u00e9velopper la force et la stabilit\u00e9 de votre corps afin qu\u2019il soit capable de g\u00e9rer ces types de d\u00e9s\u00e9quilibres et de torsions sans entra\u00eener de blessures ou de sensations d\u2019inconfort.<\/p>\n\n\n\n<p>Dans nos entra\u00eenements quotidiens, nous finissons par utiliser la m\u00eame routine, les m\u00eames muscles et mouvements \u00e0 maintes reprises.<\/p>\n\n\n\n<p><strong>De nombreux athl\u00e8tes ont reconsid\u00e9r\u00e9 l&#8217;entra\u00eenement traditionnel<\/strong>, incorporant <strong>des exercices anti-rotation<\/strong> dans leurs entra\u00eenements quotidiens pour apporter une dimension plus fonctionnelle \u00e0 leur entra\u00eenement. Pourquoi ? <strong>Parce qu&#8217;en emp\u00eachant la rotation, ils s&#8217;assurent que leur corps est capable de faire face aux exigences de forces de mouvements qui pourraient ne pas \u00eatre s\u00fbrs.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img decoding=\"async\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_fr.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105050\"\/><\/a><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">4 exercices anti-rotation \u00e0 essayer<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1 \u2013 <a href=\"https:\/\/evofitness.ch\/fr\/deadlift-avec-haltere-exercice-complet\/\">Deadlifts <\/a>unilat\u00e9raux avec poids <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tenez-vous debout, les pieds \u00e9cart\u00e9s \u00e0 la largeur des hanches, en restant au centre.<\/li>\n\n\n\n<li>Attrapez un poids unilat\u00e9ral au centre comme pour soulever un poids \u00e0 double charge.<\/li>\n\n\n\n<li>Pliez votre corps et vos genoux et soulevez le poids en position debout, comme si vous aviez la barre charg\u00e9e aux deux extr\u00e9mit\u00e9s.<\/li>\n\n\n\n<li>Ramenez doucement le poids au sol tout en gardant la barre horizontale et \u00e9galement droite aux deux extr\u00e9mit\u00e9s.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/8XOelmkvw_M\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 \u2013 Fente en rotation avec sac de sable<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Saisissez un sac de sable par les deux poign\u00e9es, les paumes face \u00e0 face.<\/li>\n\n\n\n<li>Tenez-vous droit et face \u00e0 l&#8217;avant, puis reculez d&#8217;un pied en pliant le genou en position de fente. Ne vous concentrez pas sur la flexion du genou, laissez-le se plier naturellement.<\/li>\n\n\n\n<li>Faites tourner le sac de sable en avent vers l\u2019ext\u00e9rieur, en vous penchant l\u00e9g\u00e8rement vers l&#8217;avant et sans tourner.<\/li>\n\n\n\n<li>Ramenez votre jambe en position et tenez-vous droit tout en poussant le pied arri\u00e8re vers le sol lorsque vous vous levez.<\/li>\n\n\n\n<li>Tout en revenant en position debout, faites basculer le sac de sable devant votre corps.<\/li>\n\n\n\n<li>Faites une fente arri\u00e8re avec l\u2019autre jambe, permettant au sac de sable de se balancer \u00e0 l&#8217;ext\u00e9rieur du genou avant.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/x2InSZr1x4Y\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 \u2013 Exercice genoux et poitrine<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Allongez-vous sur le dos, les genoux pli\u00e9s \u00e0 90 degr\u00e9s et les pieds fermement sur le sol.<\/li>\n\n\n\n<li>Placez vos pieds avec votre talon \u00e0 seulement quelques centim\u00e8tres de vos fesses. Appuyez sur vos talons, en soulevant lentement vos hanches et vos fesses du sol. Concentrez-vous sur le resserrement de vos fessiers.<\/li>\n\n\n\n<li>Avec les fessiers contract\u00e9s, soulevez vos hanches et amenez votre genou droit vers votre poitrine. Assurez-vous de garder votre torse immobile et de garder votre genou gauche confortablement verrouill\u00e9.<\/li>\n\n\n\n<li>Ramenez lentement votre genou vers le sol.<\/li>\n\n\n\n<li>Faites 10 r\u00e9p\u00e9titions au total sur chaque jambe.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/syAAmxjAuNE\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4 \u2013 <a href=\"https:\/\/vimeo.com\/191967185\/d4dec249b2\">Planche lat\u00e9rale<\/a><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Allongez-vous sur le sol sur le c\u00f4t\u00e9 droit et avec votre pied gauche plac\u00e9 sur le dessus de votre pied droit.<\/li>\n\n\n\n<li>Placez votre avant-bras droit sous votre \u00e9paule droite.<\/li>\n\n\n\n<li>Soulevez vos hanches tout en vous concentrant sur votre tronc. Soulevez vos hanches jusqu&#8217;\u00e0 ce que votre corps soit compl\u00e8tement align\u00e9 et droit.<\/li>\n\n\n\n<li>Maintenez cette position pendant 30 secondes maximum.<\/li>\n\n\n\n<li>R\u00e9p\u00e9tez du c\u00f4t\u00e9 gauche.<\/li>\n\n\n\n<li>Faites 10 r\u00e9p\u00e9titions au total.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Hqmb5NdId0I\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Vous vous posez des questions sur votre programme d\u2019entra\u00eenement et si vous r\u00e9pondez aux besoins de chaque muscle ? Vous&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"4 exercices anti-rotation \u00e0 inclure dans votre entra\u00eenement | EVO Fitness","_seopress_titles_desc":"Voici 4 exercices anti-rotation parfaits pour ceux qui essaient toujours de nouvelles approches d&#039;entra\u00eenement. Voici tout ce que vous devez savoir.","_seopress_robots_index":"","_seopress_analysis_target_kw":"exercices anti-rotation","footnotes":""},"categories":[1690],"tags":[1664,1714,2289],"class_list":["post-57782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bouge","tag-entrainement","tag-exercices","tag-anti-rotation"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57782"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57780"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}