{"id":57778,"date":"2020-10-07T00:00:00","date_gmt":"2020-10-06T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/prone-tuck-suspendu\/"},"modified":"2020-10-07T00:00:00","modified_gmt":"2020-10-06T22:00:00","slug":"prone-tuck-suspendu","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/apprends\/prone-tuck-suspendu\/","title":{"rendered":"Tutoriel : Prone tuck suspendu"},"content":{"rendered":"\n<p>Cherchez-vous u<strong>n exercice plus stimulant pour augmenter la force du haut de votre corps et d\u00e9velopper votre tronc ?<\/strong> Il est temps d&#8217;inclure l\u2019entra\u00eenement en suspension dans vos mouvements. Notre suggestion est<strong> le prone tuck suspendu<\/strong>, un exercice qui demande de la puissance au niveau du haut du corps tout en se concentrant sur votre tronc. Voici <a href=\"https:\/\/vimeo.com\/194321078\/140d4e0974\">tout ce que vous devez savoir \u00e0 ce sujet<\/a>.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">QUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Le prone tuck suspendu est un exercice stimulant qui d\u00e9veloppera la force et le contr\u00f4le du tronc et du haut du corps.<\/li><li>Il utilise une barre de trap\u00e8ze, mais un appareil d\u2019entra\u00eenement en suspension, comme le TRX, fera \u00e9galement l\u2019affaire.<\/li><li>On peut consid\u00e9rer cet exercice comme une progression de la planche traditionnelle. Par cons\u00e9quent, assurez-vous de pouvoir tenir une planche avec un bon contr\u00f4le avant de passer \u00e0 cet exercice.<\/li><\/ul>\n\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">COMMENT<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Agenouillez-vous \u00e0 quatre pattes avec la barre trap\u00e8ze ou le TRX derri\u00e8re vous. Vos mains doivent \u00eatre \u00e9cart\u00e9es \u00e0 largeur des \u00e9paules.<\/li><li>Lorsque vous \u00eates pr\u00eat, placez vos pieds sur la barre (ou \u00e0 l&#8217;int\u00e9rieur des sangles TRX) et soulevez votre corps en position de planche suspendue. Gardez le tronc contract\u00e9 et maintenez une position bien stable.<\/li><li>Maintenez votre position de planche en repliant lentement les genoux vers la poitrine.<\/li><li>Revenez et r\u00e9p\u00e9tez pour un nombre de r\u00e9p\u00e9titions ou un temps d\u00e9finis.<\/li><\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">POURQUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Lorsque le corps per\u00e7oit une instabilit\u00e9, il r\u00e9agit de mani\u00e8re naturelle et r\u00e9flexive pour maintenir la stabilit\u00e9. Dans cet esprit, l&#8217;entra\u00eenement en suspension (lorsqu&#8217;il est appliqu\u00e9 correctement) est un moyen fantastique d&#8217;entra\u00eener le tronc. Cependant, ne vous laissez pas berner par cet exercice, ce n\u2019est pas seulement pour le tronc, mais tout le corps qui travaille. Principalement parce que les muscles du tronc sont davantage sollicit\u00e9s par les jambes suspendues, ce qui met \u00e9galement le haut du corps au d\u00e9fi (\u00e0 savoir la poitrine, les \u00e9paules et les bras).<\/li><li>Pour tirer le meilleur parti de cet exercice, ne le consid\u00e9rez pas comme un exercice abdominal. Consid\u00e9rez-le plut\u00f4t comme un exercice de contr\u00f4le de base. Ce que vous essayez effectivement de faire, c&#8217;est de maintenir la stabilit\u00e9 et la rigidit\u00e9 de votre tronc (et de vos \u00e9paules) tout en essayant de replier vos genoux. Cela vous aidera \u00e0 rester concentr\u00e9 sur la stabilit\u00e9 du tronc et \u00e0 mieux d\u00e9velopper votre force fonctionnelle et vos mouvements.<\/li><li>Si vous n\u2019avez pas acc\u00e8s \u00e0 une barre de trap\u00e8ze ou \u00e0 un TRX, vous pouvez utiliser une swiss ball. Dans cette variante, gardez \u00e0 l&#8217;esprit que vos jambes doivent rester \u00e9lev\u00e9es au sol, ce qui mettra une charge suppl\u00e9mentaire sur vos \u00e9paules \/ vos bras. Si vous voulez une version simple et \u00e9pur\u00e9e du prone tuck suspendu, vous pouvez enlever vos chaussures et effectuer cet exercice sur un plancher en bois. Dans ce cas, vos chaussettes doivent glisser suffisamment pour cr\u00e9er un mouvement fluide lorsque vous repliez vos genoux vers l&#8217;int\u00e9rieur.<\/li><\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Maintenant que vous avez mis au d\u00e9fi votre tronc et le haut de votre corps avec le <\/strong><strong>prone tuck suspendu<\/strong><strong>, mettez au d\u00e9fi l\u2019ensemble de votre corps avec les tutoriels suivants :<\/strong><\/h4>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/fr\/fente-laterale\/\">TUTORIEL: FENTES LAT\u00c9RALES<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/fr\/entrainement-matinal-de-10-minutes\/\">VIDEO: ENTRA\u00ceNEMENT MATINAL DE 10 MINUTES<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/fr\/equilibre-sur-une-jambe\/\">TUTORIEL : EQUILIBRE SUR UNE JAMBE<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img decoding=\"async\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_fr.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105050\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Cherchez-vous un exercice plus stimulant pour augmenter la force du haut de votre corps et d\u00e9velopper votre tronc ? Il&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Prone tuck suspendu pour am\u00e9liorer la force du tronc | EVO Fitness","_seopress_titles_desc":"Vous recherchez un exercice stimulant pour augmenter la force du haut de votre corps et de votre tronc t? Essayez le prone tuck suspendu.","_seopress_robots_index":"","_seopress_analysis_target_kw":"prone tuck suspendu","footnotes":""},"categories":[1677],"tags":[1702,1932,2109,2110,2145,2277,2703,2709,2713,2764,2841,1664,1665,1688],"class_list":["post-57778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprends","tag-entrainement-fonctionnel","tag-entrainement-de-poids-corporel","tag-abdominaux","tag-controle","tag-entrainement-en-suspension","tag-force-du-tronc","tag-fitness-3","tag-balance-3","tag-exercise-3","tag-bodyweight-training-3","tag-abdominals-2","tag-entrainement","tag-exercice","tag-equilibre"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57778"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57776"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}