{"id":57727,"date":"2020-06-30T00:00:00","date_gmt":"2020-06-29T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/equilibre-sur-une-jambe\/"},"modified":"2020-06-30T00:00:00","modified_gmt":"2020-06-29T22:00:00","slug":"equilibre-sur-une-jambe","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/apprends\/equilibre-sur-une-jambe\/","title":{"rendered":"Tutoriel : Equilibre sur une jambe"},"content":{"rendered":"\n<p>L&#8217;\u00e9quilibre sur une jambe est un exercice extr\u00eamement b\u00e9n\u00e9fique et souvent n\u00e9glig\u00e9 pour d\u00e9velopper votre \u00e9quilibre. Voici comment effectuer cet exercice, ce qu&#8217;il peut apporter \u00e0 votre entra\u00eenement et pourquoi l&#8217;\u00e9quilibre sur une jambe peut vous aider \u00e0 am\u00e9liorer votre stabilit\u00e9 et votre contr\u00f4le.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">QUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>L&#8217;\u00e9quilibre sur une jambe est un exercice extr\u00eamement b\u00e9n\u00e9fique et souvent n\u00e9glig\u00e9 pour d\u00e9velopper votre \u00e9quilibre en position debout.<\/li><li>Il est g\u00e9n\u00e9ralement consid\u00e9r\u00e9 comme faisant partie des programmes de pr\u00e9vention des blessures et de r\u00e9adaptation pour le bas du corps. Cependant, plusieurs variations et progressions sont beaucoup plus difficiles et sp\u00e9cifiques pour des entra\u00eenements sportifs plus efficaces.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">COMMENT<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Tenez-vous debout, les pieds joints. Placez vos \u00e9paules en arri\u00e8re et engagez votre tronc pour maintenir une bonne posture. Vous pouvez mettre vos bras l\u00e9g\u00e8rement sur le c\u00f4t\u00e9 pour un meilleur \u00e9quilibre (si vous vous sentez instable).<\/li><li>Soulevez un pied du sol en pliant l\u00e9g\u00e8rement le genou. Ne soulevez pas la jambe trop haut. Au lieu de cela, laissez-la simplement planer l\u00e9g\u00e8rement au-dessus du sol. Essayez de maintenir une posture droite. Vous pouvez osciller l\u00e9g\u00e8rement, mais utilisez vos mains pour \u00e9quilibrer si n\u00e9cessaire.<\/li><li>Maintenez la position pendant la dur\u00e9e souhait\u00e9e. Reposez-vous et r\u00e9p\u00e9tez avec l&#8217;autre jambe.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img decoding=\"async\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_fr.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105050\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">POURQUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Apprendre \u00e0 \u00e9quilibrer est l&#8217;une de nos premi\u00e8res comp\u00e9tences en tant qu&#8217;enfants, et nous avons appris \u00e0 le faire pieds nus, ce qui a fourni une occasion d&#8217;apprentissage unique. L&#8217;\u00e9quilibre sur une jambe commence au sol, et pour en profiter, pratiquez le mouvement pieds nus (si possible).<\/li><li>Un bon \u00e9quilibre (et mouvement) n\u00e9cessite un pied stable, une cheville mobile, un genou stable et des hanches mobiles, qui doivent tous travailler en harmonie pour rester \u00e9quilibr\u00e9s. Les habitudes de vie modernes ont entra\u00een\u00e9 une faiblesse des pieds (\u00e0 cause de chaussures souvent de mauvaise qualit\u00e9), des chevilles et des hanches raides (\u00e0 cause de notre mode de vie s\u00e9dentaire). Par cons\u00e9quent, lorsqu&#8217;il s&#8217;agit d&#8217;\u00e9quilibrer, nous constatons souvent des mouvements excessifs du bas du dos et des genoux. Des chevilles et des hanches mobiles et saines sont ce qui est n\u00e9cessaire pour optimiser l&#8217;\u00e9quilibre et pour que les pieds et les genoux assurant la stabilit\u00e9. Pour lutter contre cela, essayez d&#8217;ajouter des exercices Toe-ga \u00e0 votre programme pour renforcer vos pieds et assurez-vous de mobiliser vos chevilles et vos hanches gr\u00e2ce \u00e0 des activit\u00e9s appropri\u00e9es.<\/li><li>Lorsque vous pouvez rester en \u00e9quilibre sur une jambe pendant 30 secondes, essayez d&#8217;ajouter des variations et des progressions. Par exemple, essayez d&#8217;atteindre le bras ou la jambe oppos\u00e9 vers l&#8217;avant \/ l&#8217;arri\u00e8re, ou descendez jusqu&#8217;au sol. Vous pouvez \u00e9galement tenir une bande l\u00e9g\u00e8re ou un \u00e9lastique pour d\u00e9fier vos port\u00e9es.<\/li><li>Au fur et \u00e0 mesure que vous sentez que votre \u00e9quilibre s\u2019am\u00e9liore, vous remarquerez les avantages quotidiens d\u2019une meilleure stabilit\u00e9 qui peuvent \u00e9galement am\u00e9liorer la force de vos jambes pour vos entra\u00eenements.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Single leg balance\" src=\"https:\/\/player.vimeo.com\/video\/193042583?h=badcab0402&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Maintenant que nous avons test\u00e9 votre stabilit\u00e9 avec ce tutoriel sur l&#8217;\u00e9quilibre sur une jambe, nous vous invitons \u00e0 consulter certains de nos pr\u00e9c\u00e9dents articles : <\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/evofitness.ch\/fr\/jumping-jacks\/\">Jumping jacks<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/fentes-sautees-avec-les-bras-au-dessus-de-la-tete\/\">Fentes saut\u00e9es avec les bras au-dessus de la t\u00eate<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/squat-en-maintien\/\">Squat hold<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/planche-inversee\/\">Planche invers\u00e9e<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/saut-inverse-pour-force-controle\/\">Saut invers\u00e9<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/fente-sautee\/\">Fente saut\u00e9e<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/pont-au-sol-explosif\/\">Pont au sol explosif<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/squat-sur-une-jambe\/\">Squat sur une jambe<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/fente-arriere\/\">Fente arri\u00e8re<\/a>  <\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/tutoriel-clean-kettlebell-et-presse\/\">Entra\u00eenement clean kettlebell et presse<\/a>   <\/li><\/ul>\n\n\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9quilibre sur une jambe est un exercice extr\u00eamement b\u00e9n\u00e9fique et souvent n\u00e9glig\u00e9 pour d\u00e9velopper l&#8217;\u00e9quilibre. Voici les \u00e9tapes \u00e0 suivre pour l&#8217;ex\u00e9cuter.<\/p>\n","protected":false},"author":22,"featured_media":57726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Tutoriel : Comment r\u00e9aliser correctement l&#039;\u00e9quilibre sur une jambe | EVO Fitness","_seopress_titles_desc":"L&#039;\u00e9quilibre sur une jambe est un exercice extr\u00eamement b\u00e9n\u00e9fique et souvent n\u00e9glig\u00e9 pour d\u00e9velopper l&#039;\u00e9quilibre. Voici les \u00e9tapes \u00e0 suivre pour l&#039;ex\u00e9cuter.","_seopress_robots_index":"","_seopress_analysis_target_kw":"single-leg balance","footnotes":""},"categories":[1677],"tags":[2715,2726,2764,2793,2794,1666,1667,1688,1702,2087,2110,2132,2269,2703,2709,2714],"class_list":["post-57727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprends","tag-mobility-3","tag-endurance-3","tag-bodyweight-training-3","tag-core-stability-3","tag-whole-body-3","tag-force","tag-mobilite","tag-equilibre","tag-entrainement-fonctionnel","tag-stabilite","tag-controle","tag-musculation","tag-tout-le-corps","tag-fitness-3","tag-balance-3","tag-strength-3"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57727"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57726"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}