{"id":57699,"date":"2020-04-22T00:00:00","date_gmt":"2020-04-21T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/squat-en-maintien\/"},"modified":"2020-04-22T00:00:00","modified_gmt":"2020-04-21T22:00:00","slug":"squat-en-maintien","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/apprends\/squat-en-maintien\/","title":{"rendered":"Tutoriel: Squat hold"},"content":{"rendered":"\n<p>Le squat en maintien est un <strong>exercice isom\u00e9trique difficile qui d\u00e9veloppera la force du bas du corps et un meilleur contr\u00f4le corporel<\/strong>. Restez bien en maintien et rejoignez-nous dans ce tutoriel pour apprendre comment <a href=\"https:\/\/vimeo.com\/193040761\/aa2f469027\">effectuer correctement cet exercice<\/a>.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">QUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Le squat en maintien est un exercice isom\u00e9trique difficile qui d\u00e9veloppera la force du bas du corps et un meilleur contr\u00f4le corporel.<\/li><li>Il peut \u00eatre utilis\u00e9 \u00e0 la fois comme exercice d&#8217;\u00e9chauffement, de r\u00e9cup\u00e9ration active ou comme exercice autonome dans n&#8217;importe quel entra\u00eenement.<\/li><li>L&#8217;exercice n\u00e9cessite une mobilit\u00e9 correcte de la cheville et des hanches pour se faire dans des conditions optimales.<\/li><\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">COMMENT<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Tenez-vous debout avec les pieds \u00e9cart\u00e9s \u00e0 la largeur des \u00e9paules et les pieds l\u00e9g\u00e8rement tourn\u00e9s pour plus de confort. Engagez le tronc et d\u00e9finissez les \u00e9paules. <\/li><li>Levez les bras devant la poitrine et accroupissez-vous lentement, en poussant les genoux vers l&#8217;ext\u00e9rieur, afin qu&#8217;ils restent sur les orteils. Accroupissez-vous jusqu&#8217;\u00e0 ce que le pli de la hanche soit en dessous du niveau du genou et gardez les bras devant pour un meilleur \u00e9quilibre et plus de stabilit\u00e9.<\/li><li>Maintenez cette position pendant un certain temps, en vous assurant de continuer \u00e0 respirer confortablement.<\/li><\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">POURQUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Le squat est un mouvement fondamental que tous les humains en bonne sant\u00e9 \u00e9taient capables de faire. En tant qu&#8217;enfants, le squat \u00e9tait le meilleur moyen de descendre au sol pour ramasser des objets, ainsi que notre position assise par d\u00e9faut. En vieillissant, nous perdons la capacit\u00e9 et la mobilit\u00e9 de s&#8217;accroupir. Ceci est encore aggrav\u00e9 par les machines d&#8217;exercice que nous utilisons et les mauvaises techniques qui nous apprennent \u00e0 ne s&#8217;accroupir qu&#8217;\u00e0 90 degr\u00e9s (position assise).<\/li><li>Le manque de mobilit\u00e9 de la cheville est l&#8217;une des raisons les plus courantes de ne pas pouvoir s&#8217;accroupir. Bien que notre position assise puisse \u00eatre l&#8217;une des raisons de cela, de mauvaises chaussures peuvent \u00e9galement y contribuer. Les chaussures \u00e0 talons font que les muscles du mollet restent dans une position raccourcie, ce qui entra\u00eene un raccourcissement adaptatif au fil du temps, ce qui peut limiter la dorsiflexion de la cheville, une condition qui emp\u00eache de correctement faire un squat.<\/li><li>Si vous avez des probl\u00e8mes de mobilit\u00e9 des chevilles, ceux-ci peuvent \u00eatre corrig\u00e9s avec des exercices de rouleaux de mousse ou par des \u00e9tirements r\u00e9guliers des mollets. Vous pouvez \u00e9galement commencer les squats en pla\u00e7ant vos talons sur un bloc de 1 cm, sur un poids ou sur un tapis. Cela vous permettra d&#8217;obtenir une gamme compl\u00e8te de mouvements sans effet de restriction des chevilles. \u00c0 mesure que votre flexibilit\u00e9 \/ mobilit\u00e9 s&#8217;am\u00e9liore, r\u00e9duisez la hauteur du bloc jusqu&#8217;\u00e0 ce que les pieds soient \u00e0 plat sur le sol. Cela peut prendre plusieurs mois en cas de graves probl\u00e8mes de mobilit\u00e9. Ne vous d\u00e9couragez donc pas, pers\u00e9v\u00e9rez et vous profiterez de cet excellent exercice.<\/li><li>Lorsqu&#8217;il est ex\u00e9cut\u00e9 correctement avec une mobilit\u00e9 fonctionnelle, le squat en maintien est un exercice extr\u00eamement difficile m\u00eame pour les athl\u00e8tes avertis. <\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Deep squat hold\" src=\"https:\/\/player.vimeo.com\/video\/193040761?h=aa2f469027&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"> Nous avons encore beaucoup de tutoriels \u00e0 essayer.  En voici une s\u00e9lection :  <\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li> <a href=\"https:\/\/evofitness.ch\/fr\/saut-inverse-pour-force-controle\/\">Saut invers\u00e9<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/fente-sautee\/\">Fente saut\u00e9e<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/pont-au-sol-explosif\/\">Pont au sol explosif<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/squat-sur-une-jambe\/\">Squat sur une jambe<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/fente-arriere\/\">Fente arri\u00e8re<\/a>  <\/li><li><a href=\"https:\/\/evofitness.ch\/fr\/tutoriel-clean-kettlebell-et-presse\/\">Entra\u00eenement clean kettlebell et presse<\/a> <\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le squat en maintien est un exercice d&#8217;isom\u00e9trie qui d\u00e9veloppera la force du bas du corps et le contr\u00f4le corporel. Voici comment le r\u00e9aliser.<\/p>\n","protected":false},"author":22,"featured_media":57698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Tutoriel : voici comment effectuer un squat en maintien | EVO Fitness","_seopress_titles_desc":"Le squat en maintien est un exercice d&#039;isom\u00e9trie qui d\u00e9veloppera la force du bas du corps et le contr\u00f4le corporel. Voici comment le r\u00e9aliser.","_seopress_robots_index":"","_seopress_analysis_target_kw":"squat hold","footnotes":""},"categories":[1677],"tags":[1667,2879,1702,2880,1932,2179,2242,2262,2263,2714,2715,2726,2729,2764,2774,2793,1632,2857,1666,2865],"class_list":["post-57699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprends","tag-mobilite","tag-flexibility-2","tag-entrainement-fonctionnel","tag-isometric-strength-2","tag-entrainement-de-poids-corporel","tag-jambes","tag-bas-du-corps","tag-force-isometrique","tag-stabilite-corporelles","tag-strength-3","tag-mobility-3","tag-endurance-3","tag-functional-training-3","tag-bodyweight-training-3","tag-squat-3","tag-core-stability-3","tag-flexibilite","tag-legs-3","tag-force","tag-lower-body-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57699"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57698"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}