{"id":57505,"date":"2019-09-30T00:00:00","date_gmt":"2019-09-29T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/presse-inversee\/"},"modified":"2019-09-30T00:00:00","modified_gmt":"2019-09-29T22:00:00","slug":"presse-inversee","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/apprends\/presse-inversee\/","title":{"rendered":"Tutoriel : presse invers\u00e9e"},"content":{"rendered":"\n<p>La presse invers\u00e9e est un exercice stimulant de force et de flexibilit\u00e9 du haut du corps qui ne n\u00e9cessite que votre poids. Voici comment vous devriez le faire pour plus de force et de flexibilit\u00e9<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>QUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>La presse invers\u00e9e est <strong>un exercice stimulant de force et de flexibilit\u00e9 du haut du corps qui ne n\u00e9cessite que votre poids.<\/strong><\/li><li>L\u2019exercice utilise une position inverse, inspir\u00e9e par la posture du chien au yoga. Cette position n\u00e9cessite une flexibilit\u00e9 suffisante des ischio-jambiers. Si cela manque, veillez \u00e0 utiliser les exercices modifi\u00e9s d\u00e9crits ci-dessous.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><br>COMMENT<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Commencez en position de pompes, avec le tronc engag\u00e9 et les \u00e9paules bien en place. En gardant les bras et les jambes tendus, poussez les hanches pour les amener en position de V inverse. Si vous avez des muscles ischio-jambiers courts \/ serr\u00e9s, laissez les genoux se plier un peu pour pouvoir maintenir l\u2019\u00e9quilibre sur les mains. C&#8217;est la position de d\u00e9part. Vous devriez vous sentir en \u00e9quilibre entre les bras et les jambes.<\/li><li>En gardant les \u00e9paules bien en place et le tronc engag\u00e9, baissez la t\u00eate vers vos mains en gardant les coudes sur les c\u00f4t\u00e9s. Imaginez le m\u00eame mouvement qu&#8217;une presse suspendue debout avec une barre. Maintenez le tronc contract\u00e9 lorsque vous repoussez vers la position de d\u00e9part.<\/li><li>R\u00e9p\u00e9tez pour un nombre de r\u00e9p\u00e9titions ou un temps d\u00e9finis.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/trial.evofitness.eu\/ch\/?lang=fr&amp;utm_source=website&amp;utm_medium=blog-banner&amp;utm_campaign=trial\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png\" alt=\"evo at trial cta 1day blog male fr\" class=\"wp-image-114632\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-960x422.png 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-768x338.png 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-480x211.png 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-640x281.png 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">POURQUOI<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>La position invers\u00e9e offre plusieurs avantages uniques par rapport \u00e0 la presse verticale en hauteur.<\/strong> Premi\u00e8rement, il ne n\u00e9cessite aucune charge suppl\u00e9mentaire, juste votre poids corporel. La presse invers\u00e9e place le corps dans une position d&#8217;\u00e9quilibre, ce qui n\u00e9cessite un niveau \u00e9lev\u00e9 d\u2019engagement des muscles du tronc. Deuxi\u00e8mement, la position des hanches pli\u00e9es emp\u00eache les hanches d&#8217;aider la presse. Cela force toute la ceinture scapulaire, le haut du dos et les bras \u00e0 travailler ensemble. Cela aide \u00e9galement \u00e0 augmenter la conscience de ces muscles.<\/li><li><strong>La presse invers\u00e9e est souvent l\u2019une des premi\u00e8res \u00e9tapes du cheminement vers la ma\u00eetrise des appuis.<\/strong> La force de compression dans l&#8217;inversion sera tr\u00e8s diff\u00e9rente de la compression verticale, et l&#8217;instabilit\u00e9 suppl\u00e9mentaire li\u00e9e \u00e0 l&#8217;inversion doit \u00eatre r\u00e9guli\u00e8rement entra\u00een\u00e9e. De la m\u00eame mani\u00e8re, la technique de pompes en poirier peut \u00e9galement \u00eatre utilis\u00e9e avec la presse invers\u00e9e, avant de passer \u00e0 une position compl\u00e8te du poirier.<\/li><li><strong>Enfin, la presse invers\u00e9e peut \u00eatre utile pour surmonter un plateau de force du haut du corps.<\/strong> Que vous ayez besoin d&#8217;une pause des halt\u00e8res ou que vous vous remettiez d&#8217;une blessure, cet exercice peut \u00eatre la solution de rechange id\u00e9ale pour rafra\u00eechir et revitaliser votre entra\u00eenement.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Inverted press\" src=\"https:\/\/player.vimeo.com\/video\/191978042?h=c044baa31e&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>L&#8217;AUTRES EXERCICES :<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/fr\/pompes-plus-exercice-dechauffement-mobilisation\/\">POURQUOI LES POMPES + SONT UN EXCELLENT EXERCICE D\u2019\u00c9CHAUFFEMENT ET DE MOBILISATION POUR VOS \u00c9PAULES<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/fr\/comment-realiser-lecarte-couche-trx\/\">COMMENT R\u00c9ALISER L\u2019\u00c9CART\u00c9-COUCH\u00c9 TRX POUR PLUS DE FORCE ET DE CONTR\u00d4LE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presse invers\u00e9e est un exercice stimulant de force et de flexibilit\u00e9 du haut du corps qui ne n\u00e9cessite que&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Tutoriel : comment r\u00e9aliser la presse invers\u00e9e | EVO Fitness","_seopress_titles_desc":"La presse invers\u00e9e est un exercice stimulant de force et de flexibilit\u00e9 du haut du corps. Voici comment vous devriez le faire.","_seopress_robots_index":"","_seopress_analysis_target_kw":"presse invers\u00e9e","footnotes":""},"categories":[1677],"tags":[2714,2764,2793,2840,1632,1666,1702,1932,1934,1953,2096,2098,2110,2703],"class_list":["post-57505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprends","tag-strength-3","tag-bodyweight-training-3","tag-core-stability-3","tag-shoulders-3","tag-flexibilite","tag-force","tag-entrainement-fonctionnel","tag-entrainement-de-poids-corporel","tag-stabilite-de-base","tag-entrainement-complet-du-corps","tag-bras","tag-epaules","tag-controle","tag-fitness-3"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57505"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57503"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}