{"id":57334,"date":"2019-04-29T00:00:00","date_gmt":"2019-04-28T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/comment-effectuer-le-squat-jump-avec-med-ball-pour-augmenter-la-force-lequilibre-et-la-stabilite\/"},"modified":"2019-04-29T00:00:00","modified_gmt":"2019-04-28T22:00:00","slug":"comment-effectuer-le-squat-jump-avec-med-ball-pour-augmenter-la-force-lequilibre-et-la-stabilite","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/evolue\/comment-effectuer-le-squat-jump-avec-med-ball-pour-augmenter-la-force-lequilibre-et-la-stabilite\/","title":{"rendered":"Comment effectuer le squat jump avec med ball pour augmenter la force, l&#8217;\u00e9quilibre et la stabilit\u00e9"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">QUOI <br><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Le squat jump avec med ball est <strong>une excellente progression du squat jump de base qui s\u2019appuie sur la force, l\u2019\u00e9quilibre et le contr\u00f4le<\/strong>. <\/li><li>L\u2019exercice est extensible \u00e0 tous les niveaux d\u2019habilet\u00e9, en utilisant des poids diff\u00e9rents en fonction que l\u2019accent est mis sur la force ou l\u2019endurance.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><br>COMMENT<br><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Choisissez un med ball appropri\u00e9. \u00c0 titre indicatif, visez 5 \u00e0 10% de votre poids corporel pour une vitesse d&#8217;endurance ou 10-15% de votre poids corporel pour la force-endurance. Tenez le med ball pr\u00e8s du corps \u00e0 la hauteur de la poitrine.<\/li><li>En gardant le med ball pr\u00e8s du corps, commencez les squats jump. Notez que la hauteur n&#8217;est pas importante, concentrez-vous plut\u00f4t sur la technique appropri\u00e9e et \u00e9tablissez un rythme constant.<\/li><li>Maintenez le torse engag\u00e9 tout au long de l\u2019exercice et pousser les hanches vers le haut et vers l&#8217;avant, en extension compl\u00e8te.<\/li><li>R\u00e9p\u00e9tez continuellement pour un nombre de r\u00e9p\u00e9titions ou un temps d\u00e9finis<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><br>POURQUOI<br><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Compar\u00e9 au squat jump classique, <strong>l\u2019utilisation du med ball n\u00e9cessite plus de contr\u00f4le et d\u2019\u00e9quilibre<\/strong>. Lors d&#8217;un squat jump standard, on peut corriger toute perte d&#8217;\u00e9quilibre momentan\u00e9e en effectuant de petits ajustements des bras. Lorsque vous tenez un med ball, vous retirez l&#8217;utilisation des bras pour plus de stabilit\u00e9. cela devient d&#8217;autant plus important que le poids de la balle augmente. Par cons\u00e9quent, vous constaterez souvent que les muscles centraux s\u2019engagent davantage au cours de cet exercice et vous maintiendrez naturellement une hauteur de saut plus basse jusqu\u2019\u00e0 ce que le contr\u00f4le s\u2019am\u00e9liore.<\/li><li><strong>Deux facteurs sont \u00e0 prendre en compte pour choisir le bon poids<\/strong>. Si vous souhaitez am\u00e9liorer votre endurance \/ vitesse, choisissez une balle pesant entre 5 et 10% de votre poids, et visez des s\u00e9ries de 10 \u00e0 12 r\u00e9p\u00e9titions (ou jusqu&#8217;\u00e0 ce que vous commenciez \u00e0 ralentir). Si vous voulez am\u00e9liorer votre force et votre endurance, essayez d\u2019utiliser une balle pesant entre 10 et 15% de votre poids, et visez 5 \u00e0 10 r\u00e9p\u00e9titions. Dans les deux cas, vous devez toujours maintenir un mouvement puissant avec un bon entra\u00eenement de la hanche. La vraie diff\u00e9rence reside dans le nombre de r\u00e9p\u00e9titions<\/li><li>Pour accentuer les choses, <strong>essayez de faire cet exercice entre des exercices de force complets, dans le cadre d\u2019une s\u00e9ance d\u2019entra\u00eenement intense<\/strong>.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"MB squat jump\" src=\"https:\/\/player.vimeo.com\/video\/191792274?h=1b9709ca59&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;AUTRES EXERCICES:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/evofitness.ch\/fr\/comment-effectuer-des-fentes-avec-halteres-pour-augmenter-la-force-lequilibre-et-la-stabilite\/\">COMMENT EFFECTUER DES FENTES AVEC HALT\u00c8RES POUR AUGMENTER LA FORCE, L\u2019\u00c9QUILIBRE ET LA STABILIT\u00c9<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/evofitness.ch\/fr\/burpees-pull-up\/\">COMMENT EFFECTUER DES BURPEES PULL-UP POUR UNE PUISSANCE ET UNE ENDURANCE EXPLOSIVE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>QUOI Le squat jump avec med ball est une excellente progression du squat jump de base qui s\u2019appuie sur la&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"Tutoriel : Squat jump avec med ball | EVO Fitness","_seopress_titles_desc":"Le squat jump avec med ball est une variante du squat jump de base qui met au d\u00e9fi la force, l\u2019\u00e9quilibre et la stabilit\u00e9. Voici comment l&#039;ex\u00e9cuter.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"Squat med ball","footnotes":""},"categories":[1631],"tags":[1666,1684,1715,1977,2005,2709,2714],"class_list":["post-57334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evolue","tag-force","tag-tutoriel","tag-lentrainement-fonctionnel","tag-force-des-jambes","tag-squat-med-ball","tag-balance-3","tag-strength-3"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57334"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57332"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}