{"id":57293,"date":"2019-03-28T00:00:00","date_gmt":"2019-03-27T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/comment-effectuer-des-fentes-avec-halteres-pour-augmenter-la-force-lequilibre-et-la-stabilite\/"},"modified":"2019-03-28T00:00:00","modified_gmt":"2019-03-27T23:00:00","slug":"comment-effectuer-des-fentes-avec-halteres-pour-augmenter-la-force-lequilibre-et-la-stabilite","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/apprends\/comment-effectuer-des-fentes-avec-halteres-pour-augmenter-la-force-lequilibre-et-la-stabilite\/","title":{"rendered":"Comment effectuer des fentes avec halt\u00e8res pour augmenter la force, l&#8217;\u00e9quilibre et la stabilit\u00e9"},"content":{"rendered":"<h2 style=\"text-align: justify\">QUOI<\/h2>\n<ul>\n<li style=\"text-align: justify\">Les fentes avec halt\u00e8res sont <strong>une excellente progression des fentes classiques avec votre poids corpore<\/strong>l.<\/li>\n<li style=\"text-align: justify\">Plus qu\u2019une simple progression de la force, l&#8217;utilisation des halt\u00e8res repr\u00e9sente un d\u00e9fi consid\u00e9rable pour l&#8217;\u00e9quilibre et le contr\u00f4le.<\/li>\n<li style=\"text-align: justify\">L\u2019exercice peut \u00e9galement \u00eatre effectu\u00e9 de mani\u00e8re dynamique, comme des fentes avec marche. Assurez-vous de ne le faire qu&#8217;apr\u00e8s avoir ma\u00eetris\u00e9 la technique d&#8217;une position statique.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">COMMENT<\/h2>\n<ul>\n<li style=\"text-align: justify\">Tenez un halt\u00e8re dans chaque main et tenez-vous pieds \u00e9cart\u00e9s \u00e0 la largeur des hanches. Les bras doivent rester tendus et doucement press\u00e9s par les c\u00f4t\u00e9s. Gardez l&#8217;\u00e9paule en place et le tronc engag\u00e9.<\/li>\n<li style=\"text-align: justify\">Commencez le mouvement en faisant un pas en avant et en vous penchant vers le sol. Pliez vos genoux \u00e0 90\u00b0, de mani\u00e8re \u00e0 vous sentir confortable. Si cela n\u2019est pas possible, essayez de plier les genoux \u00e0 un point plus confortable.<\/li>\n<li style=\"text-align: justify\">Gardez les halt\u00e8res en s\u00e9curit\u00e9 sur les c\u00f4t\u00e9s et engagez le tronc lorsque vous revenez debout.<\/li>\n<li style=\"text-align: justify\">R\u00e9p\u00e9tez l&#8217;op\u00e9ration sur l&#8217;autre jambe et alternez de mani\u00e8re continue pour un nombre de r\u00e9p\u00e9titions ou un temps d\u00e9finis.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">POURQUOI<\/h2>\n<ul>\n<li style=\"text-align: justify\">On pense souvent que lors d\u2019une fente, la jambe principale (la plus en avant) porte le plus de poids. A la suite de cela, beaucoup de gens se concentrent sur \u00ab pousser \u00bb la jambe avant, ce qui peut compromettre l\u2019\u00e9quilibre et la stabilit\u00e9. <strong>Au lieu de cela, placez la m\u00eame attention sur la jambe arri\u00e8re &#8211; qui sert d\u2019ancre \u00e0 la fente<\/strong>.<\/li>\n<li style=\"text-align: justify\">Tout en avan\u00e7ant, maintenez une pression \u00e9gale sur la jambe arri\u00e8re &#8211; notez que cela am\u00e9liore consid\u00e9rablement votre \u00e9quilibre. En retrouvant la position debout, vous sentirez un meilleur \u00e9quilibre. Cette petite modification devient critique lorsque vous transportez des charges, qu\u2019il s\u2019agisse d\u2019halt\u00e8res ou de sacs de base. <strong>L&#8217;ajout de poids n\u00e9cessite plus d&#8217;\u00e9quilibre \/ stabilit\u00e9<\/strong> et le maintien d&#8217;une jambe d&#8217;ancrage solide r\u00e9duira les risques d&#8217;instabilit\u00e9 et de perte d&#8217;\u00e9quilibre.<\/li>\n<li style=\"text-align: justify\">Il est \u00e9galement essentiel de faire une fente avec un pas naturel et de ne pas trop pousser &#8211; apr\u00e8s tout, c\u2019est comme \u00e7a que vous le faites dans votre vie quotidienne. C&#8217;est pourquoi nous vous conseillons de suivre le m\u00eame sch\u00e9ma lorsque vous vous entra\u00eenez.<\/li>\n<li style=\"text-align: justify\">Au fur et \u00e0 mesure que votre technique s&#8217;am\u00e9liore, essayez de remettre en cause votre \u00e9quilibre en tenant les halt\u00e8res devant les \u00e9paules (en position de rack) et m\u00eame au-dessus de votre t\u00eate. Dans tous les cas, ne compromettez pas la stabilit\u00e9 et l&#8217;\u00e9quilibre.<\/li>\n<\/ul>\n<p><iframe loading=\"lazy\" title=\"DB lunge\" src=\"https:\/\/player.vimeo.com\/video\/191792175?h=5fd0117fa4&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe><\/p>\n<p><strong>L&#8217;AUTRES EXERCICES:<\/strong><\/p>\n<p><a href=\"https:\/\/evofitness.ch\/fr\/tutoriel-le-clean-avec-barre\/\">COMMENT EFFECTUER UN POWER CLEAN POUR AVOIR PLUS DE FORCE, DE PUISSANCE ET DE CONTR\u00d4LE<\/a><\/p>\n<p><a href=\"https:\/\/evofitness.ch\/fr\/deep-squat-short-post\/\">COMMENT EFFECTUER DU DEEP SQUAT SHORT POST POUR AM\u00c9LIORER VOTRE MOBILIT\u00c9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>QUOI Les fentes avec halt\u00e8res sont une excellente progression des fentes classiques avec votre poids corporel. Plus qu\u2019une simple progression&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"Tutoriel : Fentes avec halt\u00e8res | EVO Fitness","_seopress_titles_desc":"Les fentes avec halt\u00e8res sont un exercice de progression parfait pour augmenter votre force, votre \u00e9quilibre et votre stabilit\u00e9. Apprenez \u00e0 le r\u00e9aliser ici.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"fentes avec halt\u00e8res","footnotes":""},"categories":[1677],"tags":[1666,1684,1688,1715,1989,2709,2714],"class_list":["post-57293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprends","tag-force","tag-tutoriel","tag-equilibre","tag-lentrainement-fonctionnel","tag-fentes-avec-halteres","tag-balance-3","tag-strength-3"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57293"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57294"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}