{"id":57056,"date":"2018-09-17T00:00:00","date_gmt":"2018-09-16T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/leg-curl\/"},"modified":"2018-09-17T00:00:00","modified_gmt":"2018-09-16T22:00:00","slug":"leg-curl","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/evolue\/leg-curl\/","title":{"rendered":"Comment am\u00e9liorer la stabilisation du tronc et du pelvis avec des Leg Curl"},"content":{"rendered":"<p>En effectuant cet exercice, vous renforcerez la partie post\u00e9rieure des cuisses. De plus, vous aurez \u00e9galement un meilleur contr\u00f4le de votre bassin et de votre dos, <strong>une structure fondamentale pour nos activit\u00e9s de locomotion quotidiennes<\/strong>. Le bas de votre corps, comme vous le savez, est la base de votre mouvement. De cette fa\u00e7on, cette zone de votre corps doit \u00eatre renforc\u00e9e non seulement par son travail musculaire, mais aussi par une coordination accrue.<\/p>\n<p>La n\u00e9cessit\u00e9 de renforcer les muscles post\u00e9rieurs est d\u00e9sormais encore plus importante car <strong>nous passons la majeure partie de notre journ\u00e9e assis<\/strong>. La position assise cr\u00e9e des d\u00e9s\u00e9quilibres musculaires qui r\u00e9duisent vos muscles et leur force ainsi que leur \u00e9lasticit\u00e9. Cela augmente \u00e9galement la tension dans le bas du dos.<\/p>\n<p>En ajoutant de la<strong> suspension<\/strong> \u00e0 cet exercice, vous augmentez la stabilisation des genoux, des hanches et du dos et am\u00e9liorez \u00e9galement votre coordination musculaire pour am\u00e9liorer votre mouvement.<br \/>\n&nbsp;<\/p>\n<h2>QUOI<\/h2>\n<ul>\n<li>Le Leg Curl est <strong>un exercice fonctionnel ax\u00e9 sur les quatre piliers de mouvements naturels du corps humain.<\/strong><\/li>\n<li>Il renforce les muscles post\u00e9rieurs des cuisses.<\/li>\n<li>Favorise la stabilisation des articulations du genou, du bassin et de la colonne vert\u00e9brale.<\/li>\n<li>Fait travailler votre tronc.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>COMMENT<\/h2>\n<ul>\n<li>Accrochez la barre \u00e0 l\u2019avant-dernier \u00e9tage au-dessus du sol. Allongez-vous sur le sol. La barre doit \u00eatre l\u00e9g\u00e8rement en dessous de votre genou.<\/li>\n<li>Placez vos pieds sur la barre \u00e0 m\u00eame distance que vos hanches.<\/li>\n<li>Vos hanches doivent \u00eatre soulev\u00e9es et votre poids doit \u00eatre concentr\u00e9 sur vos omoplates.<\/li>\n<li>Activez vos muscles fessiers et abdominaux afin de maintenir l\u2019\u00e9quilibre. En tendant les bras pour vous aider \u00e0 garantir cela.<\/li>\n<li>Poussez vos jambes en avant, en \u00e9tirant presque compl\u00e8tement vos genoux.<\/li>\n<li>Repoussez la barre \u00e0 nouveau<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>POURQUOI<\/h2>\n<ul>\n<li>Renforce les muscles de la cuisse et aide \u00e0 stabiliser les hanches.<\/li>\n<li>Synchronise les cuisses et les hanches, en favorisant un meilleur mouvement.<\/li>\n<li>Am\u00e9liore la posture.<\/li>\n<\/ul>\n<p><iframe loading=\"lazy\" title=\"Hamstring curl\" src=\"https:\/\/player.vimeo.com\/video\/194340019?h=8e9cf5be88&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe><\/p>\n<p><strong>L&#8217;AUTRES EXERCICES:<\/strong><\/p>\n<p><a href=\"https:\/\/evofitness.ch\/fr\/tutorial-squat-suspendu\/\">TUTORIAL: SQUAT SUSPENDU<\/a><\/p>\n<p><a href=\"\/fr\/?p=115597\">TUTORIAL: FENTE SUSPENDUE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En effectuant cet exercice, vous renforcerez la partie post\u00e9rieure des cuisses. De plus, vous aurez \u00e9galement un meilleur contr\u00f4le de&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Tutoriel: Comment faire des Leg Curl | EVO Fitness","_seopress_titles_desc":"Le Leg Curl est un exercice con\u00e7u pour vous aider \u00e0 renforcer vos ischio-jambiers tout en permettant de mieux contr\u00f4ler votre mobilit\u00e9.","_seopress_robots_index":"","_seopress_analysis_target_kw":"leg curl","footnotes":""},"categories":[1631],"tags":[1715,2708,773,1684,1689],"class_list":["post-57056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evolue","tag-lentrainement-fonctionnel","tag-bodyweight-3","tag-leg-curl","tag-tutoriel","tag-poids-corporel"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=57056"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/57056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/57054"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=57056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=57056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=57056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}