{"id":56984,"date":"2018-07-26T00:00:00","date_gmt":"2018-07-25T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/tutoriel-traction-sautee\/"},"modified":"2018-07-26T00:00:00","modified_gmt":"2018-07-25T22:00:00","slug":"tutoriel-traction-sautee","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/apprends\/tutoriel-traction-sautee\/","title":{"rendered":"Tutoriel: Traction saut\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify\">La traction saut\u00e9e vous permet d&#8217;activer votre corps de mani\u00e8re compl\u00e8te, en contractant tous les muscles en une s\u00e9quence, comme le tronc, le torse, les fessiers et les jambes.<\/p>\n<p style=\"text-align: justify\">Dans cet exercice, vous pouvez associer la force du torse, la stabilisation de l\u2019omoplate, \u00e0 la force du tronc sur diff\u00e9rents niveaux verticaux. Cette combinaison totale cr\u00e9e<strong> un grand mouvement fonctionnel qui vise \u00e0 soulever le centre de la masse corporelle<\/strong> tout en se concentrant sur la prise de force.<\/p>\n<p style=\"text-align: justify\">Cet exercice implique des mouvements comme grimper, sauter, tirer et descendre de mani\u00e8re contr\u00f4l\u00e9e. Nous pouvons utiliser ce mod\u00e8le de mouvement par exemple pour l&#8217;escalade ou le basketball.<\/p>\n<p style=\"text-align: justify\">Lorsque vous sautez, attrapez et tirez, vous g\u00e9n\u00e9rez un d\u00e9placement vertical qui implique un m\u00e9canisme d&#8217;extension triple incluant la cheville, le genou et la hanche. Combin\u00e9 avec le mouvement de traction, nous pouvons <strong>activer les abdominaux<\/strong>, connect\u00e9s au muscle grand dorsal et aux bras, <strong>cr\u00e9ant un mouvement du corps efficace<\/strong> avec une charge partag\u00e9e par la structure du corps et les articulations.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">QUOI<\/h2>\n<ul style=\"text-align: justify\">\n<li>La traction saut\u00e9e est un exercice de traction corporelle et fonctionnel<\/li>\n<li>Renforce la r\u00e9sistance et la stabilit\u00e9 et la stabilisation du tronc<\/li>\n<li>G\u00e9n\u00e8re le transfert de puissance et de force du bas vers le haut du corps<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">COMMENT<\/h2>\n<ul style=\"text-align: justify\">\n<li>Debout sous la barre de traction Queenax, faites un petit saut pour attraper les poign\u00e9es, stabilisez votre omoplate et engagez tous les muscles du tronc.<\/li>\n<li>Avec un petit \u00e9lan, saisissez la barre et remontez votre corps jusqu&#8217;\u00e0 ce que le menton atteigne la barre ou la d\u00e9passe<\/li>\n<li>Retournez en position initiale pour ralentir le mouvement jusqu&#8217;\u00e0 ce que les bras soient \u00e9tendus<\/li>\n<li>Atterissez doucement sur le sol<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">POURQUOI<\/h2>\n<ul>\n<li style=\"text-align: justify\">Augmente la force fonctionnelle et la mobilit\u00e9 dans un mode d&#8217;activation complet du corps<\/li>\n<li style=\"text-align: justify\">Favorise l&#8217;activation du torse<\/li>\n<li style=\"text-align: justify\">Favorise la coordination<\/li>\n<li style=\"text-align: justify\">Favorise la mobilit\u00e9 articulaire<\/li>\n<li style=\"text-align: justify\">Augmente la puissance<\/li>\n<li style=\"text-align: justify\">Augmente l&#8217;agilit\u00e9<\/li>\n<\/ul>\n<p><iframe loading=\"lazy\" title=\"Jump pull up\" src=\"https:\/\/player.vimeo.com\/video\/194351298?h=ef1a04b339&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe><\/p>\n<p><strong>D&#8217;AUTRES EXERCICES:<\/strong><\/p>\n<p><a href=\"https:\/\/evofitness.ch\/fr\/tutoriel-traction-impulsion\/\">TUTORIEL: TRACTION IMPULSION<\/a><\/p>\n<p><a href=\"https:\/\/evofitness.ch\/fr\/tutorial-saut-croise-rotation\/\">TUTORIAL: SAUT CROIS\u00c9 AVEC ROTATION<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La traction saut\u00e9e vous permet d&#8217;activer votre corps de mani\u00e8re compl\u00e8te, en contractant tous les muscles en une s\u00e9quence, comme&#8230;<\/p>\n","protected":false},"author":17,"featured_media":56982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Tutoriel: Traction saut\u00e9e - EVO Fitness","_seopress_titles_desc":"La traction saut\u00e9e est un exercice de mouvement naturel fait avec le queenax. Augmentez le d\u00e9fi de vos tractions en introduisant un mouvement de saut.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Traction saut\u00e9e","footnotes":""},"categories":[1677],"tags":[1715,1798,1684],"class_list":["post-56984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprends","tag-lentrainement-fonctionnel","tag-traction-sautee","tag-tutoriel"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/56984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=56984"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/56984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/56982"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=56984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=56984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=56984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}