{"id":113130,"date":"2025-06-18T05:00:00","date_gmt":"2025-06-18T03:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/?p=113130"},"modified":"2025-06-13T13:57:44","modified_gmt":"2025-06-13T11:57:44","slug":"manger-en-regardant-la-tele","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/fr\/blog\/decouvre\/manger-en-regardant-la-tele\/","title":{"rendered":"Manger en regardant la t\u00e9l\u00e9 peut-il pousser \u00e0 trop manger ?"},"content":{"rendered":"\n<p><strong>Imagine ceci : tu as eu une longue journ\u00e9e de travail.<\/strong> Tu rentres enfin chez toi, tu enfiles quelque chose de confortable, et l\u00e0, tout ce que tu veux, c\u2019est te d\u00e9tendre. <strong>Alors tu r\u00e9chauffes des restes ou tu commandes ton plat r\u00e9confortant pr\u00e9f\u00e9r\u00e9, tu t\u2019installes sur le canap\u00e9 et tu appuies sur play pour le prochain \u00e9pisode de cette s\u00e9rie que tu as regard\u00e9e en rafale.<\/strong> C\u2019est un rituel familier, simple, apaisant, presque automatique. <strong>Dans le monde hyperconnect\u00e9 d\u2019aujourd\u2019hui, manger tout en regardant un \u00e9cran semble naturel.<\/strong><\/p>\n\n\n\n<p>Et honn\u00eatement, qui pourrait t\u2019en vouloir ? Apr\u00e8s une grosse journ\u00e9e, associer ton repas ou ton snack pr\u00e9f\u00e9r\u00e9 \u00e0 un nouvel \u00e9pisode ou \u00e0 une relecture r\u00e9confortante, c\u2019est m\u00e9rit\u00e9. <strong>Mais m\u00eame si \u00e7a peut sembler \u00eatre le summum de la d\u00e9tente, manger devant un \u00e9cran peut transformer une s\u00e9ance de binge-watching en une s\u00e9ance de binge-food.<\/strong> Aujourd\u2019hui, on est l\u00e0 pour r\u00e9pondre \u00e0 cette question : <strong>est-ce que manger en regardant la t\u00e9l\u00e9vision te pousse \u00e0 trop manger ?<\/strong><br>D\u00e9couvrons-le.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Est-ce que manger en regardant la t\u00e9le pousse \u00e0 trop manger ?<\/h2>\n\n\n\n<p>Eh bien, la r\u00e9ponse n\u2019est pas aussi simple qu\u2019on pourrait le croire. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/35697153\/\"><strong>Certaines \u00e9tudes sugg\u00e8rent<\/strong><\/a> que <strong>le fait d\u2019\u00eatre distrait en mangeant peut parfois amener les gens \u00e0 manger moins ou \u00e0 ne pas manger du tout.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/evofitness.ch\/fr\/abonnements\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/12\/evo-ch-standard-sales-campaign-blog-fr.png\" alt=\"evo ch standard sales campaign blog fr\" class=\"wp-image-114618\" style=\"width:1024px\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/12\/evo-ch-standard-sales-campaign-blog-fr.png 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/12\/evo-ch-standard-sales-campaign-blog-fr-960x422.png 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/12\/evo-ch-standard-sales-campaign-blog-fr-768x338.png 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/12\/evo-ch-standard-sales-campaign-blog-fr-480x211.png 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/12\/evo-ch-standard-sales-campaign-blog-fr-640x281.png 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/12\/evo-ch-standard-sales-campaign-blog-fr-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Mais avant de crier au hack minceur, il y a un hic. <strong>Bien que les distractions puissent supprimer l\u2019app\u00e9tit, elles perturbent aussi la capacit\u00e9 de ton cerveau \u00e0 enregistrer ce que tu as mang\u00e9 et combien tu as mang\u00e9. Il est donc plus difficile de se sentir rassasi\u00e9 et satisfait, ce qui peut entra\u00eener une suralimentation.<\/strong><\/p>\n\n\n\n<p><strong>Il n\u2019est donc pas surprenant que le temps pass\u00e9 devant un \u00e9cran \u2014 en particulier la t\u00e9l\u00e9vision \u2014 ait \u00e9t\u00e9 associ\u00e9 \u00e0 plusieurs reprises \u00e0 la suralimentation et \u00e0 la prise de poids.<\/strong> <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0195666314000130\"><strong>Une \u00e9tude r\u00e9cente<\/strong><\/a> a m\u00eame montr\u00e9 que regarder la t\u00e9l\u00e9 en mangeant augmente l\u2019apport \u00e9nerg\u00e9tique global, et peut contribuer \u00e0 l\u2019ob\u00e9sit\u00e9.<\/p>\n\n\n\n<p><strong>Il y a une autre couche \u00e0 cela : le comportement s\u00e9dentaire.<\/strong> Les personnes qui mangent souvent devant un \u00e9cran ont tendance \u00e0 \u00eatre <strong>moins actives dans l\u2019ensemble<\/strong>, et ce manque de mouvement est <strong>un facteur connu de prise de poids et de probl\u00e8mes de sant\u00e9<\/strong>.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Comment \u00e9viter cela<\/h3>\n\n\n\n<p>Il existe quelques strat\u00e9gies conscientes qui peuvent t\u2019aider \u00e0 profiter de tes programmes favoris et \u00e0 garder tes habitudes sous contr\u00f4le.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">1 &#8211; S\u00e9parer les deux habitudes<\/h4>\n\n\n\n<p>Manger devant une s\u00e9rie, c\u2019est tentant. Mais si tu vas le faire, essaie de mettre sur pause et installe-toi \u00e0 table ou dans la cuisine. <strong>\u00catre attentif au moment et \u00e0 l\u2019endroit o\u00f9 tu manges aide ton cerveau \u00e0 enregistrer le repas, ce qui te rend moins susceptible d\u2019abuser.<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">2 &#8211; Choisis bien tes collations<\/h4>\n\n\n\n<p>Si tu grignotes, <strong>privil\u00e9gie des glucides complexes ou des options riches en prot\u00e9ines qui calent vraiment. Les crackers complets, le ma\u00efs souffl\u00e9 nature ou le yaourt grec sont de bonnes options.<\/strong> \u00c9vite les snacks sucr\u00e9s, sal\u00e9s ou bourr\u00e9s de caf\u00e9ine, surtout en soir\u00e9e.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">3 &#8211; Fixe-toi des limites<\/h4>\n\n\n\n<p><strong>Pr\u00e9pare ton repas avant de lancer ta s\u00e9rie. Et pendant que t\u2019y es, choisis aussi combien de temps tu vas regarder.<\/strong> Fixer des limites c\u00f4t\u00e9 grignotage et temps d\u2019\u00e9cran t\u2019aide \u00e0 rester attentif, m\u00eame si \u00e7a veut dire mettre l\u2019\u00e9pisode en pause pour finir ton plat.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">4 &#8211; Garde tes mains occup\u00e9es<\/h4>\n\n\n\n<p>On grignote souvent plus par ennui que par faim. <strong>Des activit\u00e9s comme tricoter, dessiner ou presser une balle anti-stress peuvent t\u2019occuper et, en m\u00eame temps, t\u2019\u00e9viter de replonger dans le paquet de snacks.<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/trial.evofitness.eu\/ch\/?lang=fr&amp;utm_source=website&amp;utm_medium=blog-banner&amp;utm_campaign=trial\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png\" alt=\"evo at trial cta 1day blog male fr\" class=\"wp-image-114632\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr.png 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-960x422.png 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-768x338.png 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-480x211.png 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-640x281.png 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-fr-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Imagine ceci : tu as eu une longue journ\u00e9e de travail. Tu rentres enfin chez toi, tu enfiles quelque chose&#8230;<\/p>\n","protected":false},"author":5,"featured_media":113123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Manger en regardant la t\u00e9l\u00e9 peut-il pousser \u00e0 trop manger ? | %%sitetitle%%","_seopress_titles_desc":"On comprend l'attrait de manger devant la t\u00e9l\u00e9, mais cela peut conduire \u00e0 manger plus que raison. Voici ce qu'il faut savoir.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[2702],"tags":[2322,2897,2957,2958],"class_list":["post-113130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decouvre","tag-alimentation-saine","tag-nutrition-2","tag-manger-trop","tag-television"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/113130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/comments?post=113130"}],"version-history":[{"count":2,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/113130\/revisions"}],"predecessor-version":[{"id":113135,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/posts\/113130\/revisions\/113135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media\/113123"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/media?parent=113130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/categories?post=113130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/fr\/wp-json\/wp\/v2\/tags?post=113130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}