{"id":58865,"date":"2024-11-18T00:00:00","date_gmt":"2024-11-17T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/50-40-30-20-10-bodyweight-workout\/"},"modified":"2024-11-18T00:00:00","modified_gmt":"2024-11-17T23:00:00","slug":"50-40-30-20-10-bodyweight-workout","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/move\/50-40-30-20-10-bodyweight-workout\/","title":{"rendered":"Workout der Woche: 50-40-30-20-10 Bodyweight-Workout"},"content":{"rendered":"\n<p><strong>ALLE FITNESSLEVEL <\/strong>\/ 50-40-30-20-10-Workout \/ 15 Minuten<\/p>\n\n\n\n<p><strong>Ausr\u00fcstung<\/strong>: Trainingsmatte<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Klassische Workouts laufen in der Regel nach einem strengen Muster ab: Gleich viele S\u00e4tze und Wiederholungen, gleiche Dauer. <strong>Und obwohl Kontinuit\u00e4t f\u00fcr das Erreichen deiner Ziele von entscheidender Bedeutung ist, kann das Festhalten an der immer gleichen Routine langfristig zu einem <\/strong><a href=\"\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Plateau f\u00fchren &#8211; die Fortschritte bleiben aus und die Motivation ist im Keller<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n\n<p>Genau hier kommen neue und dynamischere Ans\u00e4tze ins Spiel, die dir helfen, aus dem gewohnten Trott auszubrechen und die mit einer neuen, anspruchsvolleren Struktur frischen Wind in dein Training bringen.<\/p>\n\n\n\n<p>Und genau das ist das Ziel dieses<strong> 50-40-30-20-10-Workouts. <\/strong>Das System ist einfach: <strong>Die Zahlen geben an, wie viele Wiederholungen du von jeder \u00dcbung in jeder Runde machst.<\/strong> Lass dich jedoch nicht von der Tatsache t\u00e4uschen, dass diese Session aus lediglich <strong>3 \u00dcbungen <\/strong>besteht und nur <strong>15 Minuten <\/strong>dauert; dies ist trotzdem ein sehr forderndes und effektives Konditionstraining.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Push-ups<\/li>\n\n\n\n<li>Squats<\/li>\n\n\n\n<li>Scissors<\/li>\n<\/ol>\n\n\n\n<p><strong>Startklar? Lass uns loslegen!<\/strong><\/p>\n\n\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT SETUP<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>5 Runden<\/li>\n\n\n\n<li>3 \u00dcbungen<\/li>\n\n\n\n<li>50 Wiederholungen pro \u00dcbung in der 1. Runde<\/li>\n\n\n\n<li>10 Wiederholungen weniger in jeder folgenden Runde<\/li>\n\n\n\n<li>Dauer: 15 Minuten<\/li>\n<\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT \u00dcBUNGSLISTE<\/h2>\n\n\n\n<p><strong>5 <\/strong><strong>Runden<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">1 &#8211; PUSH-UPS<\/h3>\n\n\n\n<p><strong>50-40-30-20-10 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Beginne in der Plank-Position. Die Arme sind gestreckt, die Schultern sind \u00fcber den Handgelenken und der K\u00f6rper bildet eine gerade Linie. Spanne deine K\u00f6rpermitte und die Ges\u00e4ssmuskeln an.<\/li>\n\n\n\n<li>Bewege den gesamten K\u00f6rper so tief wie m\u00f6glich in Richtung Boden. Dabei sollten deine Schultern \u00fcber den Handgelenken bleiben.<\/li>\n\n\n\n<li>Dr\u00fcck deinen K\u00f6rper wieder nach oben und kehre in die Ausgangsposition zur\u00fcck.<\/li>\n\n\n\n<li>Absolviere die gew\u00fcnschten Wiederholungen oder auf Zeit.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/kCHJu6jqI-w?si=CL89zy8lZUDdKVww\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; SQUATS<\/h3>\n\n\n\n<p><strong>50-40-30-20-10 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Stehe aufrecht, die F\u00fcsse schulterbreit auseinander.<\/li>\n\n\n\n<li>Spanne deine K\u00f6rpermitte an und bewege dich in Richtung Boden in eine Hockposition. Achte darauf, dass deine Knie auf der Linie deiner F\u00fcsse bleiben. Halte die Bauch- und Ges\u00e4ssmuskeln angespannt, um deine H\u00fcfte zu kontrollieren und die Bewegung zu stabilisieren. Benutze deine Arme, um das Gleichgewicht zu halten.<\/li>\n\n\n\n<li>Dr\u00fccke die F\u00fcsse fest in den Boden und gehe so tief wie m\u00f6glich in die Hocke, ohne dass du dabei die Fersen anhebst oder Schmerzen im unteren R\u00fccken versp\u00fcrst.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/tf1C-qf-u1c?si=up_WyfCZCS-S2GT3\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; SCISSORS<\/h3>\n\n\n\n<p><strong>50-40-30-20-10 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lege dich mit gestreckten Beinen und \u00fcber der Brust gekreuzten Armen auf den R\u00fccken. Nun hebe beide Beine leicht vom Boden ab.<\/li>\n\n\n\n<li>Spanne deine K\u00f6rpermitte an und hebe deinen Oberk\u00f6rper leicht an.<\/li>\n\n\n\n<li>Kreuze in der Luft das rechte Bein \u00fcber das linke. Dann spreize deine Beine wieder leicht und kreuze das linke Bein \u00fcber das rechte.<\/li>\n\n\n\n<li>\u00dcberkreuze 30 Sekunden lang deine Beine im Wechsel.<\/li>\n\n\n\n<li>Senke Beine und Oberk\u00f6rper langsam wieder auf die Matte und ruhe dich kurz aus.<\/li>\n<\/ul>\n\n\n\n<div class=\"youtube-container\"> <iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/v32QdMrffJk?si=xarypPTt3JlY7EVd\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Wenn du an der Herausforderung dieses 50-40-30-20-10-Workouts Spa\u00df hattest, wirst du diese hier lieben:<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/evofitness.ch\/de\/12-min-amrap-oberkoerper-workout\/\">12 Min. AMRAP-Oberk\u00f6rper-Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/15min-stoffwechsel-kraft-workout\/\">15 Min. Stoffwechsel-Kraft-Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/12-min-unterkoerper-strength-und-conditioning-workout\/\">12 Min. Unterk\u00f6rper Strenght &amp; Conditioning Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/30-min-emom-full-body-workout\/\">30 Min. EMOM Full-Body Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/30-min-zone-2-cardio-workout\/\">30 Min. Zone-2-Cardio-Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/15-min-unterkoerper-kraft-workout\/\"> 15 Min. Unterk\u00f6rper-Kraft-Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/20min-emom-kraft-workout\/\">20 Min. EMOM-Kraft-Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/30min-oberkoerper-kraft-workout\/\">30 Min.&nbsp;Oberk\u00f6rper-Kraft-Work<\/a><a href=\"https:\/\/evofitness.at\/30min-oberkoerper-kraft-workout\/\">out<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/35min-full-body-kraft-workout\/\">35 Min. Full-Body-Kraft-Workout<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/16 Min. R\u00fccken-und-Schulter-Workout\">16 Min. R\u00fccken-und-Schulter-Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/20-minuten-stoffwechsel-kraft-workout\/\">20 Min. Stoffwechsel-Kraft-Workout<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.ch\/de\/25-min-schulter-kraft-workout\/\">25 Min. Schulter-Kraft-Workout<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105054\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de.jpg 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-960x422.jpg 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-768x338.jpg 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-480x211.jpg 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-640x281.jpg 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-720x316.jpg 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ALLE FITNESSLEVEL \/ 50-40-30-20-10-Workout \/ 15 Minuten Ausr\u00fcstung: Trainingsmatte Klassische Workouts laufen in der Regel nach einem strengen Muster ab:&#8230;<\/p>\n","protected":false},"author":26,"featured_media":58864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Workout der Woche: 50-40-30-20-10 Bodyweight-Workout | EVO Fitness","_seopress_titles_desc":"Manchmal brauchst du f\u00fcr ein intensives Workout einfach nur deine Kraft. Dieses Bodyweight 50-40-30-20-10- Workout beweist es.","_seopress_robots_index":"","_seopress_analysis_target_kw":"50-40-30-20-10- Workout","footnotes":""},"categories":[102],"tags":[1343,1443,1465,1479,1533],"class_list":["post-58865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-move","tag-bodyweight-2","tag-wow-2","tag-50-40-30-20-10-workout-2","tag-bodyweight-workout-2","tag-workout-der-woche-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/58865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=58865"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/58865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/58864"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=58865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=58865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=58865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}