{"id":58202,"date":"2022-05-02T00:00:00","date_gmt":"2022-05-01T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/pyramid-functional-workout-2\/"},"modified":"2022-05-02T00:00:00","modified_gmt":"2022-05-01T22:00:00","slug":"pyramid-functional-workout-2","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/move\/pyramid-functional-workout-2\/","title":{"rendered":"Workout der Woche: 20 Min. Pyramid Functional Workout"},"content":{"rendered":"\n<p><strong>ALL<\/strong><strong>E<\/strong><strong> <\/strong><strong>FITNESS<\/strong><strong>LEVEL <\/strong>\/ Pyramid Functional Workout \/ 20 Minuten<\/p>\n\n\n\n<p><strong>Ausr\u00fcstung<\/strong>: Trainingsmatte<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Im Gegensatz zu Pyramid Schemes (zu deutsch: Schneeballsysteme) <strong>kommt Pyramidentraining tats<\/strong><strong>\u00e4<\/strong><strong>chlich allen zugute<\/strong>; Dar\u00fcber hinaus ist es eine <strong>angenehme und effiziente M<\/strong><strong>\u00f6<\/strong><strong>glichkeit, um die Fitness zu verbessern<\/strong>. Wie der Name es bereits verr\u00e4t, folgen diese Workouts einer Pyramidenstruktur. Das bedeutet, dass sich sowohl <strong>die Anzahl an Wiederholungen als auch die<\/strong><strong> Intensit<\/strong><strong>\u00e4t <\/strong><strong>zun\u00e4chst erh\u00f6hen<\/strong><strong>, <\/strong><strong>bevor sie dann wieder abnehmen<\/strong>.<\/p>\n\n\n\n<p>Das Konzept dahinter ist das Progressionsprinzip, das besagt, dass du deine <strong>Trainingsroutine \u00e4ndern solltest, sobald sich dein K\u00f6rper daran gew\u00f6hnt hat<\/strong>. \u00a0Was das genau bedeutet, ist dir \u00fcberlassen: Du kannst Gewicht, Dauer oder Intensit\u00e4t erh\u00f6hen, oder eine ganz neue Sportart ausprobieren. Zu guter Letzt <strong>f\u00e4llt diese Trainingsart unter die Intervalltrainingsmethode<\/strong>, die, wie du bereits wei\u00dft, beim <a href=\"https:\/\/evofitness.ch\/de\/tabata-emom-amrap-hiit\/\">Muskelaufbau und beim Abnehmen hilft<\/a>.<\/p>\n\n\n\n<p>Dieses <strong>Py<\/strong><strong>ramid <\/strong><strong>F<\/strong><strong>unctional <\/strong><strong>W<\/strong><strong>orkout<\/strong> besteht aus <strong>4 <\/strong><strong>\u00dcbungen<\/strong>. 3 von ihnen sind Teil der Haupt\u00fcbungsgruppe, die \u00fcber <strong>9 Runden<\/strong> mit einer jeweils vordefinierten Anzahl an Wiederholungen ausgef\u00fchrt werden: <strong>5, 10, 15, 20, 25, 20, 15, 10 und 5<\/strong>. Am Ende jeder Runde machst du 50 Wiederholungen der 4. \u00dcbung. Lege nach Bedarf Pausen ein. Insgesamt sollte dieses Training <strong>20 Minuten<\/strong> dauern.&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Crawling Push-up<\/li><li>Squat to Lunge<\/li><li>Flutter Kicks<\/li><li>Squat Jacks<\/li><\/ol>\n\n\n\n<p><strong>Lasst uns gemeinsam die Pyramide erklimmen<\/strong><strong>!<\/strong><\/p>\n\n\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT SETUP<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Die ersten drei \u00dcbungen \u2013 5, 10, 15, 20, 25, 20, 15, 10 und 5 Wiederholungen<\/li><li>9 Runden<\/li><li>Nach jeder Runde 50 Wiederholungen der 4. \u00dcbung<\/li><li>Pausiere je nach Bedarf<\/li><li>20 Minuten<\/li><li>Ausr\u00fcstung: Trainingsmatte<\/li><\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">DU TRAINIERST ZU HAUSE? KEIN PROBLEM.<\/h3>\n\n\n\n<p>EVO f\u00f6rdert nat\u00fcrliche Bewegung und f\u00fcr unsere Workouts, wie dieses hier, ben\u00f6tigst du wenig bis keine Ausr\u00fcstung und minimalen Raum, weshalb du sie \u00fcberall machen kannst.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT \u00dcBUNGSLISTE<\/h2>\n\n\n\n<p><strong>9 <\/strong><strong>Runden<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">1 &#8211; CRAWLING PUSH-UP<\/h3>\n\n\n\n<p><strong>5, 10, 15, 20, 25, 20, 15, 10, 5 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Suche dir einen weichen Untergrund (im Fitnessstudio nutzen wir den Kunstrasenbereich) und gehe in die Liegest\u00fctz-Position, das ist die Ausgangsposition. Dein K\u00f6rper sollte sehr stabil sein.\u00a0<\/li><li>F\u00fchre nun eine <a href=\"https:\/\/evofitness.ch\/de\/liegestuetze-korrekt-ausfuehren\/\">Liegest\u00fctze<\/a> aus, indem du deine Arme beugst und deine Ellbogen etwas nach hinten in Richtung deines Rumpfes bringst.\u00a0<\/li><li>Wenn du etwas \u00fcber dem Boden angekommen bist, dr\u00fccke dich in einer explosionsartigen Bewegung wieder hoch.\u00a0\u00a0<\/li><li>Krabbele ungef\u00e4hr einen halben Meter nach vorne und wiederhole Schritt 1-3.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/m5t3ZLu1MZI\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; SQUAT TO LUNGE<\/h3>\n\n\n\n<p><strong>5, 10, 15, 20, 25, 20, 15, 10, 5 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Stelle dich aufrecht hin &#8211; das ist die Startposition.<\/li><li>Mache eine Kniebeuge und komm sofort wieder hoch.<\/li><li>Mache jetzt einen Lunge auf einer Seite und gehe dann wieder Startposition.<\/li><li>Jetzt folgt eine Kniebeuge und ein Lunge auf der anderen Seite.<\/li><li>Kehre in die Ausgangsposition zur\u00fcck und wiederhole.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/F880k7yms_8\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; FLUTTER KICKS<\/h3>\n\n\n\n<p><strong>5, 10, 15, 20, 25, 20, 15, 10, 5 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Lege dich mit dem R\u00fccken auf den Boden und positioniere deinen R\u00fccken im 45 Grad Winkel.<\/li><li>Nutze deine Ellbogen, um dich abzust\u00fctzen.&nbsp;<\/li><li>Strecke deine Beine so gerade wie m\u00f6glich aus.<\/li><li>Hebe deine Fersen explosiv vom Boden hoch und mache f\u00fcr die angegebene Zeit hoch und runter Bewegungen.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/8aeHZvWnSbU\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; SQUAT JACKS<\/h3>\n\n\n\n<p><strong>50 <\/strong><strong>Wiederholungen<\/strong><strong> <\/strong><strong>nach jeder Runde<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Beginne in der Squat Position mit geschlossenen F\u00fc\u00dfen. Deine H\u00e4nde ber\u00fchren fast den Boden neben deinen Kn\u00f6cheln.&nbsp;<\/li><li>Springe explosiv in die weite Kniebeuge und \u00f6ffne dabei deine Arme \u00fcber deinem Kopf wie bei einem Jumping Jack.&nbsp;<\/li><li>Springe wieder in die erste Squat Position mit geschlossenen Beinen, gebeugten Knien und den Armen seitlich.<\/li><li>Achte darauf, deinen Brustkorb w\u00e4hrend der Bewegung ausgestreckt zu halten.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/5sU-XwTYlFw\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Dieses 20 Min. Pyramid Functional Workout hat ganz sch\u00f6n Power. Weitere coole Workouts findest du hier:<\/h4>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-83532e61-7995-424d-99ee-d090765bd094\"><li><a href=\"https:\/\/evofitness.ch\/de\/20-min-functional-full-body-workout\/\">20 Min. functional Full-body Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/15-min-rowing-workout\/\">15 Min. Rowing Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/10-min-functional-oberkoerper-workout\/\">10 Min. functional Oberk\u00f6rper Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/20-min-unterkoerper-dumbbell-workout\/\">20 Min. Unterk\u00f6rper Dumbbell Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/20-min-strength-cable-workout\/\">20 Min Strength Cable Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/18-min-emom-workout\/\">18 Min. EMOM Workout f\u00fcr Kraft<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/15-min-fullbody-tabata-workout\/\">15 Min. Full-body Tabata Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/10-min-bodyweight-cardio-workout\/\">10 Min. Bodyweight Cardio Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/20-min-schulter-und-rumpf-workout\/\">20 Min. Schulter und Rumpf Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/40-min-functional-fullbody-workout\/\">40 Min. functional Full-body Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/20-min-functional-partner-workout\/\">20 Min. functional Partner Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/20-min-cardio-und-core-workout\/\">20 Min. Cardio und Core Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/40-min-functional-strength-workout\/\">40 Min. Functional Strength Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/10-min-bodyweight-amrap-workout\/\">10 Min. Bodyweight AMRAP Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/15-min-functional-strength-workout\/\">15 Min. functional strength Workout f\u00fcr Kraft<\/a><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/trial.evofitness.eu\/ch\/?lang=de&amp;utm_source=website&amp;utm_medium=blog-banner&amp;utm_campaign=trial\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-de.png\" alt=\"evo at trial cta 1day blog male de\" class=\"wp-image-114642\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-de.png 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-de-960x422.png 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-de-768x338.png 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-de-480x211.png 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-de-640x281.png 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2019\/08\/evo-at-trial-cta-1day-blog-male-de-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ALLE FITNESSLEVEL \/ Pyramid Functional Workout \/ 20 Minuten Ausr\u00fcstung: Trainingsmatte Im Gegensatz zu Pyramid Schemes (zu deutsch: Schneeballsysteme) kommt&#8230;<\/p>\n","protected":false},"author":17,"featured_media":58201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[102],"tags":[1307,1449,1521,1533],"class_list":["post-58202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-move","tag-workout-2","tag-functional-workout-2","tag-pyramid-workout-2","tag-workout-der-woche-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/58202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=58202"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/58202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/58201"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=58202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=58202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=58202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}