{"id":57920,"date":"2021-04-19T00:00:00","date_gmt":"2021-04-18T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/full-body-workout-kraft-beweglichkeit\/"},"modified":"2021-04-19T00:00:00","modified_gmt":"2021-04-18T22:00:00","slug":"full-body-workout-kraft-beweglichkeit","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/move\/full-body-workout-kraft-beweglichkeit\/","title":{"rendered":"Workout der Woche: Full-Body Workout f\u00fcr Kraft und Beweglichkeit"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FULL-BODY WORKOUT F\u00dcR KRAFT UND BEWEGLICHKEIT<\/strong><\/h2>\n\n\n\n<p><strong>ALLE FITNESSLEVEL <\/strong>\/ Full-Body Workout \/ 30 Minuten<\/p>\n\n\n\n<p><strong>Ausr\u00fcstung<\/strong>: Kettlebells &amp; Elastikband<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Die besten Training Sessions sind <\/strong><a href=\"https:\/\/evofitness.ch\/de\/tabata-workout-3\/\">kurz und einfach<\/a><strong>.<\/strong> Das beweisen wir heute mit einem kurzen, aber sehr effektiven Full-Body Workout, kreiert von <strong>Ally Njama, Personal Trainer bei <\/strong><a href=\"https:\/\/evofitness.ch\/de\/evo-bern\/\">EVO Bern in der Schweiz<\/a>.<\/p>\n\n\n\n<p>Diese Training Session dauert je nach deinem Fitnesslevel ungef\u00e4hr 30 Minuten. Sie besteht nur aus 3 \u00dcbungen und kommt mit wenig Gym Ausr\u00fcstung aus. Alles, was du ben\u00f6tigst, sind ein paar Kettlebells und ein Elastikband. Jede \u00dcbung wird 10 Mal \u00fcber 3 S\u00e4tze ausgef\u00fchrt.<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Kettlebell Squat zu Upright Row mit Resistenzband<\/li><li>Loaded Beast zu Front Kick Through<\/li><li>Kettlebell Total-Body Combo<\/li><\/ol>\n\n\n\n<p><strong>Bist du bereit? Los geht\u2019s!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_switzerland\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de.jpg\" alt=\"Instagram - EVO Fitness Switzerland\" class=\"wp-image-105054\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de.jpg 1024w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-960x422.jpg 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-768x338.jpg 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-480x211.jpg 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-640x281.jpg 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2024\/05\/evo-ch-blog_de-720x316.jpg 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT AUFBAU<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>3 \u00dcbungen<\/li><li>10 Wiederholungen<\/li><li>3 S\u00e4tze<\/li><li>30 Minuten<\/li><li>Ausr\u00fcstung: Kettlebells &amp; Resistenzband<\/li><\/ul>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">DU TRAINIERST ZU HAUSE? KEIN PROBLEM.<\/h3>\n\n\n\n<p>Keine Sorge, falls du nicht die notwendige Ausr\u00fcstung f\u00fcr dieses Workout hast &#8211; du kannst die jeweiligen Ger\u00e4te einfach durch Alltagsgegenst\u00e4nde ersetzen, oder die \u00dcbungen wie unten angegeben modifizieren.<\/p>\n\n\n\n<p><strong>Alternative <\/strong><strong>Ausr\u00fcstung<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Kettlebell Squat zu Upright Row mit Resistenzband<ul><li>Kettlebell = 5 Liter Flasche &nbsp;<\/li><\/ul><\/li><li>Kettlebell Total-Body Combo<ul><li>Kettlebells = zwei Wasserflaschen, oder nur dein K\u00f6rpergewicht<\/li><\/ul><ul><li>Resistenzband = mach die \u00dcbungen ohne Band &nbsp;<\/li><\/ul><\/li><\/ul>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT \u00dcBUNGSLISTE<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1 &#8211; KETTLEBELL SQUAT ZU UPRIGHT ROW MIT RESISTENZBAND<\/h3>\n\n\n\n<p><strong>10 Wiederholungen, 3 S\u00e4tze, 20 Sekunden Pause zwischen den S\u00e4tzen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Nimm dir eine Kettlebell und platziere sie auf dem Boden zwischen deinen F\u00fc\u00dfen. Zieh das Band durch den Griff und sichere die Enden jeweils unter einem Fu\u00df.&nbsp;<\/li><li>Fass die Kettlebell am Griff. Lass den Po sinken und schieb ihn nach hinten, sodass du in der <a href=\"https:\/\/evofitness.ch\/de\/tiefe-kniebeuge-hip-out\/\">Squat<\/a> Position landest.<\/li><li>Kreiere eine metabolische Bewegung: Ziehe beim Strecken der Beine aus der Squat Position den Griff der Kettlebell bis zu deinem Schl\u00fcsselbein hoch. Die Ellbogen f\u00fchren dabei die Bewegung.&nbsp;<\/li><li>Lass dann die Kettlebell langsam wieder in die Ausgangsposition sinken und wiederhole die Bewegung.&nbsp;<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/4_2H_q-1dAI\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe><\/div>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; LOADED BEAST ZU FRONT KICK THROUGH<\/h3>\n\n\n\n<p><strong>10 Wiederholungen, 3 S\u00e4tze, 30 Sekunden Pause zwischen den S\u00e4tzen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Beginne in einer Loaded Beast Position: Sie \u00e4hnelt der Child\u2019s Pose, aber deine Knie ber\u00fchren hierbei nicht den Boden.&nbsp;<\/li><li>Springe mit deinen Fu\u00dfballen explosionsartig nach vorne.&nbsp;<\/li><li>Strecke dein rechtes Bein komplett und spitze die Zehen. F\u00fchre deinen linken Arm in die Guard Position, indem du den Ellbogen beugst und deine Hand nach vorne zeigt. &nbsp;<\/li><li>Invertiere die Loaded Beast Position und wechsle die Seiten. Nachdem du die gleiche Bewegung auf der linken Seite gemacht hast, ist die erste Wiederholung geschafft.&nbsp;<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/nWGgoo-jZjo\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; KETTLEBELL TOTAL-BODY COMBO<\/h3>\n\n\n\n<p><strong>10 <\/strong><strong>Wiederholungen, 3 <\/strong><strong>S\u00e4tze, 30 <\/strong><strong>Sekunden Pause zwischen den S\u00e4tzen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Nimm dir zwei Kettlebells und stelle dich aufrecht hin: Spanne Ges\u00e4\u00dfmuskeln und Rumpf an.<\/li><li>Schiebe die H\u00fcfte nach hinten und lass die Kettlebells zu Boden sinken.&nbsp;<\/li><li>Halte die Kettlebells fest und springe in einer explosiven Bewegung mit den Fu\u00dfballen nach hinten. Strecke dabei die Beine aus, sodass du in der Plank Position landest.&nbsp;<\/li><li>Mache nun eine Push-up.&nbsp;<\/li><li>Wenn du wieder in der Plank bist, mache mit deinem rechten Arm eine Row Bewegung. Rumpf und Ges\u00e4\u00dfmuskeln bleiben dabei angespannt.&nbsp;<\/li><li>Wiederhole die Liegest\u00fctze und vervollst\u00e4ndige die Row mit deinem linken Arm.&nbsp;<\/li><li>Das war die erste Wiederholung.&nbsp;<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/NndeBF95nNk\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Wenn dir dieses Kettlebell Total Body Workout gefallen hat, wirst du diese Challenges lieben:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/evofitness.ch\/de\/45-min-kraft-und-ausdauer-workout\/\">45 Min. Kraft und Ausdauer Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/35-min-kettlebell-workout\/\">35 Min. Kettlebell Workout f\u00fcr Kraft und Power<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/ganzkorper-dumbbell-workout\/\">Ganzk\u00f6rper Dumbbell Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/funktionelles-schulter-workout\/\">Funktionelles Schulter Workout f\u00fcr Kraft und Kontrolle<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/35-min-funktionelles-kraft-workout\/\">35 Min. funktionelles Kraft Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/30-min-funktionelles-workout\/\">30 Min. funktionelles Workout f\u00fcr Kraft<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/30-min-pilates-workout\/\">30 Min. Pilates Workout f\u00fcr Kraft und Power<\/a><\/li><li><a href=\"https:\/\/evofitness.ch\/de\/30-min-hiit-workout\/\">30 Min. Ganzk\u00f6rper HIIT Workout<\/a><\/li><\/ul>\n\n\n","protected":false},"excerpt":{"rendered":"<p>FULL-BODY WORKOUT F\u00dcR KRAFT UND BEWEGLICHKEIT ALLE FITNESSLEVEL \/ Full-Body Workout \/ 30 Minuten Ausr\u00fcstung: Kettlebells &amp; Elastikband Die besten&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Full-Body Workout f\u00fcr Kraft und Beweglichkeit | EVO Fitness","_seopress_titles_desc":"Die besten Workouts sind einfach und effektiv. Das beweisen wir mit einem Full-Body Workout f\u00fcr Kraft, kreiert von unserem PT Ally Njama.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Full-Body Workout","footnotes":""},"categories":[102],"tags":[1307,1443,1446,1533],"class_list":["post-57920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-move","tag-workout-2","tag-wow-2","tag-kettlebell-workout-2","tag-workout-der-woche-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57920"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57780"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}