{"id":57797,"date":"2020-10-28T00:00:00","date_gmt":"2020-10-27T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/scissor-kicks-2\/"},"modified":"2020-10-28T00:00:00","modified_gmt":"2020-10-27T23:00:00","slug":"scissor-kicks-2","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/learn\/scissor-kicks-2\/","title":{"rendered":"Tutorial: Scissor Kicks"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bauchmuskeln sind in der Fitnessindustrie ein beliebtes Thema und dementsprechend gibt es unz\u00e4hlige Abs-\u00dcbungen. Auch wir werden oft gefragt, <strong>welche die besten Sixpack-\u00dcbungen sind<\/strong>. Darauf antworten wir als erstes, dass du nicht nach einem Sixpack streben musst \u2013 <strong>ein starker Rumpf bedeutet nicht unbedingt sich abzeichnende Bauchmuskeln<\/strong>. Wenn wir aber dennoch <a href=\"https:\/\/vimeo.com\/191960222\/15c1cca7f9\">eine \u00dcbung<\/a> f\u00fcr einen kr\u00e4ftigen Rumpf empfehlen m\u00fcssten, dann sind es definitiv die Scissor Kicks. Warum? Lies weiter und lass dich \u00fcberzeugen.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WAS<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Scissor Kicks ist eine herausfordernde \u00dcbung, um Kraft und Kontrolle im Rumpf zu entwickeln.<\/li><li>Diese \u00dcbung hat eine lange Geschichte und wird von vielen als \u201eoldschool\u201c bezeichnet. Dank der wachsenden Beliebtheit von Eigengewichtstraining, Krafttraining und Gymnastik in der Fitnessindustrie wird sie allerdings immer h\u00e4ufiger verwendet.<\/li><\/ul>\n\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WIE<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Lege dich mit \u00fcber deinem Kopf ausgestreckten Armen auf den R\u00fccken. Spanne den Rumpf an und beuge das Becken leicht (sodass dein K\u00f6rper eine \u201eTellerform\u201c bildet).<\/li><li>Schwinge die Arme in einer schnellen Bewegung, bis sie ein Bein ber\u00fchren. Arme und Beine bleiben dabei ausgestreckt. Lass die Arme kontrolliert wieder sinken und schwinge sie dann erneut, um das andere Bein zu ber\u00fchren.<\/li><li>Wiederhole das Ganze f\u00fcr eine bestimmte Anzahl an Wiederholungen oder eine festgelegte Zeit.<\/li><\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WARUM<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Scissor Kicks konzentrieren sich haupts\u00e4chlich auf die vorderen Rumpfmuskeln. Aufgrund der schnellen Bewegung setzt diese \u00dcbung gute Koordination, Gleichgewicht und Kontrolle voraus. Wichtig zu beachten ist, dass die schwereren Beine effektiv durch die leichteren Arme ausbalanciert werden m\u00fcssen. Wenn die hinteren Oberschenkelmuskeln k\u00fcrzer oder wenig beweglich sind, k\u00f6nnen die Beine zudem nicht so hochgehoben werden. In diesem Fall muss der Oberk\u00f6rper noch weiter reichen, was wiederum das Gleichgewicht beeinflusst.<\/li><li>Sollten deine hinteren Oberschenkelmuskeln zu kurz oder zu eng sein, kannst du deine Beine leicht beugen (auch wenn es sich dadurch einfacher anf\u00fchlt). Arbeite in diesem Fall an der Flexibilit\u00e4t dieser Muskeln, um die Scissor Kicks irgendwann mit ausgestreckten Beinen ausf\u00fchren zu k\u00f6nnen.<\/li><li>Diese \u00dcbung setzt zwar vor allem eine gute Koordination zwischen Ober- und Unterk\u00f6rper voraus, um das Gleichgewicht zu halten, aber auch das Halten eines stabilen Rumpfes spielt w\u00e4hrend der Bewegung eine wichtige Rolle. Wenn der Rumpf erm\u00fcdet, kann es schwierig werden, die Neigung des Beckens und somit die \u201aTellerform\u2018 zu halten, was wiederum zu einem Verlust des Gleichgewichts f\u00fchren kann. Baue daher deine Leistung langsam auf und mache zu Anfang lieber weniger Wiederholungen, aber achte auf gute Kontrolle und den richtigen Rhythmus.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Scissor kicks\" src=\"https:\/\/player.vimeo.com\/video\/191960222?h=15c1cca7f9&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Komm nach den Scissor Kicks blo\u00df nicht aus dem Rhythmus und check direkt weitere Tutorials aus:<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/evofitness.ch\/de\/inverted-jump-mehr-kraft-koerperkontrolle\/\">TUTORIAL: INVERTED JUMP<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/evofitness.ch\/de\/kettlebell-workout\/\">WORKOUT DES MONATS: NO WAY OUT<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/evofitness.ch\/de\/reverse-lunge\/\">TUTORIAL: REVERSE LUNGE<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/linktr.ee\/evofitness_switzerland\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1125\" src=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-scaled.png\" alt=\"blog banners follow us evo blog de\" class=\"wp-image-115718\" style=\"width:1024px\" srcset=\"https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-scaled.png 2560w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-960x422.png 960w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-1920x844.png 1920w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-768x338.png 768w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-1536x675.png 1536w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-2048x900.png 2048w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-480x211.png 480w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-640x281.png 640w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-720x316.png 720w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-1160x510.png 1160w, https:\/\/evofitness.ch\/wp-content\/uploads\/2020\/03\/blog-banners-follow-us_evo-blog_de-1440x633.png 1440w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bauchmuskeln sind in der Fitnessindustrie ein beliebtes Thema und dementsprechend gibt es unz\u00e4hlige Abs-\u00dcbungen. Auch wir werden oft gefragt, welche&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[101],"tags":[2107,2108,2192,2763,750,1304,1307,1308,1321,1331,1377,1929],"class_list":["post-57797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn","tag-bauchmuskeln-2","tag-kontrolle-2","tag-eigengewichtstraining-2","tag-bodyweight-training-2","tag-rumpfkraft","tag-exercise-2","tag-workout-2","tag-fitness-2","tag-balance-2","tag-sport-2","tag-functional-fitness-2","tag-gleichgewicht-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57797"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57796"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}