{"id":57675,"date":"2020-03-23T00:00:00","date_gmt":"2020-03-22T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/jumping-lunge-2\/"},"modified":"2020-03-23T00:00:00","modified_gmt":"2020-03-22T23:00:00","slug":"jumping-lunge-2","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/learn\/jumping-lunge-2\/","title":{"rendered":"Tutorial: Jumping Lunge"},"content":{"rendered":"\n<p>Die Jumping Lunge ist eine Weiterentwicklung der traditionellen Lunge f\u00fcr mehr Schnelligkeit und Power. In diesem Tutorial erkl\u00e4ren wir dir, wie du diese \u00dcbung korrekt ausf\u00fchrst und somit deine allgemeine sportliche Leistung verbesserst.  <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WAS<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Die Jumping Lunge ist <strong>eine Weiterentwicklung der traditionellen Lunge, die (wie der Name verr\u00e4t) einen Sprung enth\u00e4lt. <\/strong><\/li><li>Wenn sie bei einem hohen Tempo ausgef\u00fchrt wird, trainiert sie das Gleichgewicht und verbessert die K\u00f6rperhaltung.<\/li><li>Wenn du die Technik beherrschst, kannst du das Tempo und damit die Intensit\u00e4t erh\u00f6hen, um dein Herz-Kreislauf-System herauszufordern. <\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WIE<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Beginne stehend, deine Arme liegen seitlich an deinem K\u00f6rper an. Spanne den Rumpf an und richte die Schultern.<\/li><li>Halte den Oberk\u00f6rper aufrecht, mache einen kleinen Sprung und spreize die Beine, sodass du in einem Ausfallschritt landest. Achte darauf, dass der Abstand zwischen den F\u00fc\u00dfen nicht zu gro\u00df ist, sodass du das Gleichgewicht halten kannst und sinke mit dem hinteren Knie so tief wie m\u00f6glich. Lass deine Arme in entgegengesetzte Richtung zu den Beinen locker schwingen. <\/li><li>Sobald du am tiefsten Punkt ankommst, mache einen explosionsartigen Sprung und bringe die H\u00fcfte nach oben. Wenn du an den h\u00f6chsten Punkt gelangst, wechsle die Beine und sinke wieder in den Ausfallschritt (auf der anderen Seite).<\/li><li>Wiederhole die Bewegung f\u00fcr eine bestimmte Anzahl an Wiederholungen oder eine festgelegte Dauer. <\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WARUM<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Die Einbeziehung asymmetrischer Bewegungen in Workouts ist ideal, um Bewegungsungleichgewichte zu beheben<\/strong>. Der Ausfallschritt ist eine der wenigen Unterk\u00f6rper-\u00dcbungen, die das effektiv tut. <\/li><li><strong>Um Kraft aufzubauen f\u00fcgen viele der \u00dcbung Gewichte in Form von Kurzhanteln, Langhanteln oder Kettlebells hinzu, sobald sie den klassischen Ausfallschritt beherrschen.<\/strong> Auch ein h\u00f6heres Tempo und kraftvollere Bewegungen machen die \u00dcbung herausfordernder. <\/li><li><strong>Das Erh\u00f6hen des Tempos erfordert bei jeder \u00dcbung eine gute K\u00f6rperkontrolle und einen ausgepr\u00e4gten Gleichgewichtssinn und erh\u00f6ht die Anforderungen an das Herz-Kreislauf-System. <\/strong>Das schlagartige Erh\u00f6hen des Pulsschlags ist beim Erlernen dieser \u00dcbung der am meisten herausfordernde Faktor. Genau aus diesem Grund passt die Jumping Lunge ideal in ein hochintensives Zirkeltraining. <\/li><li>Wer ein kurzes und effektives Ganzk\u00f6rper-Workout zusammenstellen m\u00f6chte, das Kraft aufbaut und die Leistungsf\u00e4higkeit erh\u00f6ht, <strong>sollte auf jeden Fall die Jumping Lunge in seinen Trainingsplan aufnehmen.<\/strong><\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"padding:67.5% 0 0 0;position:relative;\"><iframe src=\"https:\/\/player.vimeo.com\/video\/193044441?portrait=0\" style=\"position:absolute;top:0;left:0;width:100%;height:100%;\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/div><script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>ANDERE \u00dcBUNGEN:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/de\/medizinball-tornado\/\">TUTORIAL: FLOOR BRIDGE<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/de\/medizinball-tornado\/\">TUTORIAL: MEDIZINBALL TORNADO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Jumping Lunge ist eine Weiterentwicklung der traditionellen Lunge f\u00fcr mehr Schnelligkeit und Power. In diesem Tutorial erkl\u00e4ren wir dir,&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[101],"tags":[1315,1352,1429,1461,1638,1639,1686,1927,2108,2177,2248,2763,867,1309],"class_list":["post-57675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn","tag-power-2","tag-strength-2","tag-speed-2","tag-legs-2","tag-koordination-2","tag-kraft-2","tag-flexibilitat-2","tag-eigengewichttraining-2","tag-kontrolle-2","tag-beine-2","tag-schnelligkeit-2","tag-bodyweight-training-2","tag-unterkorper","tag-functional-training-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57675"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57674"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}