{"id":57634,"date":"2020-02-05T00:00:00","date_gmt":"2020-02-04T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/box-jump-ubungen\/"},"modified":"2020-02-05T00:00:00","modified_gmt":"2020-02-04T23:00:00","slug":"box-jump-ubungen","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/learn\/box-jump-ubungen\/","title":{"rendered":"Box Jump \u00dcbungen f\u00fcr mehr Explosivit\u00e4t"},"content":{"rendered":"\n<p>Box Jump \u00dcbungen sind ideal, <strong>um explosive Power aufzubauen<\/strong>. Die plyometrische Bewegung kr\u00e4ftigt die gr\u00f6\u00dften Muskeln im Unterk\u00f6rper (Ges\u00e4\u00df-, Oberschenkel-, Waden- und Beinbeugemuskeln).<\/p>\n\n\n\n<p>Sie erfordern einen maximalen Input innerhalb k\u00fcrzester Zeit, weshalb sie bei allen Trainern sehr beliebt sind. Das Tolle an dieser \u00dcbung ist ihre Vielseitigkeit \u2013 du kannst du H\u00f6he der Box variieren und sie somit deinen Fitnesszielen anpassen.<\/p>\n\n\n\n<p>Du w\u00fcnschst dir eine kr\u00e4ftigere Muskulatur und bessere athletische F\u00e4higkeiten? Dann d\u00fcrfen die Box Jump \u00dcbungen in deinem Workout nicht fehlen. Wir stellen dir verschiedene Pylo-Powerbewegungen vor, <strong>die Abwechslung in deine Trainingsroutine bringen und deine Fitness herausfordern.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Wie man die Box Jump \u00dcbungen richtig ausf\u00fchrt <\/h2>\n\n\n\n<p>Achte auf die korrekte Form und Haltung, bevor du mit den Box Jump \u00dcbungen anf\u00e4ngst: <\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Stelle dich mit den F\u00fc\u00dfen schulterbreit auseinander hin. Achte darauf, dass dein R\u00fccken gerade und aufrecht ist. Finde die richtige Entfernung zur Box: nicht zu weit weg, aber auch nicht so nah, dass du mit den Schienbeinen dagegen sto\u00dfen k\u00f6nntest. <\/li><li>Beuge die Knie und springe dann auf die Box, indem du mit den Armen Schwung holst und die F\u00fc\u00dfe in einer explosiven Bewegung vom Boden abdr\u00fcckst. Lande so sanft wie m\u00f6glich.<\/li><li>Springe nun wieder in die Ausgangsposition zur\u00fcck. Auch hier gilt, je sanfter die Landung, desto besser der Sprung. Falls du die Box Jump \u00dcbungen zum ersten Mal machst, kannst du beim Heruntersteigen erst ein und dann das andere Bein absetzen. Das trainiert die Ges\u00e4\u00dfmuskeln und beugt Gelenkschmerzen vor. <\/li><li>Mache insgesamt 3 S\u00e4tze mit jeweils f\u00fcnf Wiederholungen, um Explosivit\u00e4t aufzubauen.<\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Kreative Box Jump \u00dcbungen f\u00fcr explosive Power<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Power Pistol Squat Box Jump<\/h3>\n\n\n\n<p><strong>So geht\u2019s:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Stelle dich mit angewinkelten und am K\u00f6rper anliegenden Armen hinter die Box.<\/li><li>Stelle dich mit dem linken Fu\u00df auf die rechte Ecke der Box. Halte das rechte Bein etwas vor dir neben der Box.<\/li><li>Beuge dein linkes Knie langsam in einem 90 Grad Winkel w\u00e4hrend du die rechte Ferse zu Boden sinken l\u00e4sst. F\u00fcr ein besseres Gleichgewicht kannst du die Arme ausstrecken. <\/li><li>Strecke das Bein wieder, sodass du zur Ausgangsposition zur\u00fcckkehrst. <\/li><li>Mache insgesamt 12 Wiederholungen, dann wechsle die Seite und wiederhole.<\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Box Jump Burpees<\/h3>\n\n\n\n<p><strong>So geht\u2019s:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>F\u00fchre einen Box Jump aus.<\/li><li>Beuge deine Knie, sobald du wieder in der Ausgangsposition ankommst, schiebe die H\u00fcfte nach hinten und sinke in eine Kniebeugeposition. <\/li><li>Springe mit den F\u00fc\u00dfen in eine Plank-Position, sodass dein K\u00f6rper von deinem Kopf zu deinen F\u00fc\u00dfen eine gerade Linie bildet. <\/li><li>Springe so nach vorne, dass deine F\u00fc\u00dfe rechts und links von deinen Armen landen.<\/li><li>Strecke deine Arme in die H\u00f6he und springe in einer explosiven Bewegung in die Luft. <\/li><li>Schlie\u00dfe direkt nach dem Landen einen weiteren Box Jump an. <\/li><li>Mache insgesamt zwei S\u00e4tze mit jeweils 10 Wiederholungen.<\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Box Jump \u00dcbungen mit Gewichten<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Nimm in jede Hand eine Hantel; die Arme liegen seitlich am K\u00f6rper an.<\/li><li>Beuge in einer schnellen Bewegung die Knie. <\/li><li>Lasse die Gewichte beim Box Jump zu Boden sinken.<\/li><li>Springe wieder in die Ausgangsposition, f\u00fchre einen Bizeps Curl aus und wiederhole die \u00dcbung 12 Mal.<\/li><\/ol>\n\n\n\n<p><strong>Effektives Training sollte spielerisch und progressiv sein. Unsere kreativen \u00dcbungen bringen Abwechslung in deine Workout-Routine und bringen deine functional Fitness auf ein ganz neues Level. Noch mehr Inspiration findest du auf dem (explosiven) <\/strong><a href=\"https:\/\/evofitness.ch\/de\/blog-evo\/\"><strong>EVO Blog<\/strong><\/a><strong>.<\/strong><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Box Jump \u00dcbungen sind ideal, um explosive Power aufzubauen. Die plyometrische Bewegung kr\u00e4ftigt die gr\u00f6\u00dften Muskeln im Unterk\u00f6rper (Ges\u00e4\u00df-, Oberschenkel-,&#8230;<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Box Jump \u00dcbungen f\u00fcr mehr Explosivit\u00e4t | EVO Fitness","_seopress_titles_desc":"Box Jump \u00dcbungen sind ideal, um Explosivit\u00e4t aufzubauen. Hier ist alles was du wissen musst, um diese \u00dcbungen korrekt auszuf\u00fchren.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Box Jump \u00dcbungen","footnotes":""},"categories":[101],"tags":[1317,1331,1377,1422,1991,2227,1304,1307,1309],"class_list":["post-57634","post","type-post","status-publish","format-standard","hentry","category-learn","tag-training-2","tag-sport-2","tag-functional-fitness-2","tag-box-jump-2","tag-funktionell-2","tag-explosiv-2","tag-exercise-2","tag-workout-2","tag-functional-training-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57634"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57634\/revisions"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}