{"id":57611,"date":"2020-01-09T00:00:00","date_gmt":"2020-01-08T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/angled-push-up-2\/"},"modified":"2020-01-09T00:00:00","modified_gmt":"2020-01-08T23:00:00","slug":"angled-push-up-2","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/learn\/angled-push-up-2\/","title":{"rendered":"Tutorial: Angled Push-up"},"content":{"rendered":"\n<p>Die Angled Push-up ist eine tolle Suspensionstraining-\u00dcbung f\u00fcr den Rumpf und Oberk\u00f6rper. Wir erkl\u00e4ren dir, wie du die Angled Push-up korrekt ausf\u00fchrst und Kraft und K\u00f6rperkontrolle verbesserst.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>WAS    <\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Die Angled Push-up ist <strong>eine \u00dcbung f\u00fcr das Suspensionstraining, die an einem Trapez-Reck (superfunktionelles Reck) ausgef\u00fchrt wird.<\/strong>    <\/li><li>\u00c4hnlich wie traditionelle Suspensionsger\u00e4te (wie z.B. die TRX), bietet das Trapez-Reck eine instabile Trainingsumgebung. Zusammen mit der richtigen Technik erh\u00e4ltst du ein optimales Trainingsger\u00e4t zur Verbesserung der Gesundheit deiner Gelenke. <\/li><li>Diese \u00dcbung trainiert den gesamten K\u00f6rper mit einem besonderen Fokus auf die Rumpfmuskeln, Brust und Schultern.<\/li><\/ul>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">WIE<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>H\u00e4nge das Reck etwas tiefer als auf Brusth\u00f6he. Stelle dich eine Arml\u00e4nge entfernt hinter das Reck und fasse es mit den H\u00e4nden schulterbreit auseinander.<\/li><li>Lehne dich mit ausgestreckten Armen zum Reck hin, um in die Ausgangsposition zu gelangen. Spanne den Rumpf leicht an und richte die Schultern. <\/li><li>Sinke jetzt mit dem Brustkorb zum Reck. Achte darauf, deinen K\u00f6rper gerade und deinen Rumpf angespannt zu halten. Pausiere kurz und kehre dann zur Ausgangsposition zur\u00fcck.<\/li><li>Wiederhole die Bewegung f\u00fcr eine bestimmte Anzahl an Wiederholungen oder eine festgelegte Zeit. <\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><br>WARUM<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Im Vergleich zu TRX kann die Nutzung eines geraden Recks die Belastung der Handgelenke reduzieren<\/strong> und eignet sich daher ideal, um die gleichen Bewegungen alternativ, beziehungsweise auf eine andere Art und Weise zu trainieren. Wenn du ausreichend Kraft in den Handgelenken aufgebaut hast, kannst du zu den TRX Griffen wechseln oder Liegest\u00fctze auf dem Boden ausf\u00fchren. <\/li><li><strong>Viele halten Suspensionstraining f\u00fcr eine leichtere Alternative im Vergleich zu Training mit freien Gewichten. <\/strong>Dabei wird allerdings oft vergessen, dass Suspensionstraining ein direktes Feedback zur Position der Gelenke und der K\u00f6rperhaltung gibt und dich dadurch dazu zwingt, auf eine korrekte Haltung zu achten. Zudem dr\u00fcckst\/ziehst du beim Suspensionstraining weniger Gewicht, was eine geringere Verletzungsgefahr und eine gr\u00f6\u00dfere Kontrolle der Bewegung erm\u00f6glicht. Genau aus diesen Gr\u00fcnden ist Suspensionstraining ideal, um sich nach einer Verletzung zu erholen und ein Trainingsplateau zu \u00fcberwinden &#8211; auch als Erg\u00e4nzung zu Freigewichtstraining. <\/li><li><strong>Zu guter Letzt m\u00f6chten wir dich noch auf die Anpassungsf\u00e4higkeit von Suspensionstraining hinweisen. <\/strong>Mit steigender Kraft kannst du die Position deines K\u00f6rpers ver\u00e4ndern, um effektiv mehr Belastung zu kreieren. Im Fall der Angled Push-up kannst du zum Beispiel das Reck tiefer h\u00e4ngen, damit die \u00dcbung noch herausfordernder wird. <\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Angled push up\" src=\"https:\/\/player.vimeo.com\/video\/194040237?h=e8ee48ff17&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>ANDERE \u00dcBUNGEN:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/de\/dumbbell-chest-press\/\">TUTORIAL: DUMBBELL CHEST PRESS<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/de\/kinesis-chest-press\/\">TUTORIAL: KINESIS CHEST PRESS<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Angled Push-up ist eine tolle Suspensionstraining-\u00dcbung f\u00fcr den Rumpf und Oberk\u00f6rper. Wir erkl\u00e4ren dir, wie du die Angled Push-up&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[101],"tags":[2207,527,1306,1308,1352,1639,1991,2085,2143,2144],"class_list":["post-57611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn","tag-rumpftraining-2","tag-oberkorper","tag-stability-2","tag-fitness-2","tag-strength-2","tag-kraft-2","tag-funktionell-2","tag-stabilitat-2","tag-superfunktionell-2","tag-suspensionstraining-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57611"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57610"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}