{"id":57549,"date":"2019-11-11T00:00:00","date_gmt":"2019-11-10T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/oberschenkeldehnung\/"},"modified":"2019-11-11T00:00:00","modified_gmt":"2019-11-10T23:00:00","slug":"oberschenkeldehnung","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/learn\/oberschenkeldehnung\/","title":{"rendered":"Tutorial: Superfunktionelle Oberschenkeldehnung"},"content":{"rendered":"\n<p>Mit  einer tollen superfunktionalen \u00dcbung starten wir in den neuen Monat. In diesem Tutorial erkl\u00e4ren wir dir, wie du superfunktionelle Oberschenkeldehnung korrekt ausf\u00fchrst, um deine Beweglichkeit und Flexibilit\u00e4t zu erh\u00f6hen. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>WAS    <\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Die superfunktionelle Oberschenkeldehnung ist <strong>eine hervorragende Alternative zur klassischen Beweglichkeits\u00fcbung.    <\/strong><\/li><li>Sie eignet sich sowohl zum Aufw\u00e4rmen, als auch zum Abk\u00fchlen. <\/li><\/ul>\n\n\n\n\n\n<h2 class=\"wp-block-heading\"><br>WIE<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>H\u00e4nge das Reck etwas tiefer als auf H\u00fcfth\u00f6he und stelle dich dahinter. Stelle einen Fu\u00df gegen das Reck und beuge dein Knie. Halte die B\u00e4nder an beiden Seiten, um das Gleichgewicht zu halten. In dieser Position solltest du auf einem Bein relativ gerade stehen. Das ist die Ausgangsposition der superfunktionellen Oberschenkeldehnung.<\/li><li>Strecke dein Bein langsam und beuge die H\u00fcfte leicht, bis du ein leichtes Ziehen in deinen Oberschenkelmuskeln sp\u00fcrst. Halte die Position f\u00fcr einige Sekunden und kehre dann langsam wieder in die Ausgangsposition zur\u00fcck. Die gesamte Bewegung sollte 8-10 Sekunden dauern.<\/li><li>Mache 5 bis 10 Wiederholungen \u2013 Achte darauf, dich langsam zu bewegen.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><br>WARUM<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Diese Variante der klassischen Oberschenkeldehnung hat einige Vorteile und Besonderheiten.    <\/li><li><strong>Erstens erfordert die stehende Position mehr Balance. <\/strong>Aus diesem Grund ist diese Variante m\u00f6glicherweise nicht f\u00fcr Anf\u00e4nger geeignet; Daf\u00fcr erm\u00f6glicht sie eine bessere Isolierung der Oberschenkelmuskulatur ohne \u00fcberm\u00e4\u00dfigen Verlust der Haltung.    <\/li><li><strong>Zweitens erm\u00f6glicht die stehende Position eine bessere Beugung der H\u00fcfte<\/strong> &#8211; eine Bewegung, die f\u00fcr das Strecken der Oberschenkelmuskulatur unerl\u00e4sslich ist. Beim herk\u00f6mmlichen sitzenden Oberschenkeldehnen wird die Wirbels\u00e4ule h\u00e4ufig auf Kosten der Oberschenkel gedehnt, da das Beugen des H\u00fcftgelenks schwer zu \u201csp\u00fcren\u201d ist. Da die H\u00fcftbewegung im Stehen nicht eingeschr\u00e4nkt ist, kann die Oberschenkelmuskulatur effektiver gedehnt werden.<\/li><li><strong>Nicht zuletzt erh\u00f6ht das Strecken und Beugen des Beins die Durchblutung der gedehnten Muskeln<\/strong>, wodurch die Flexibilit\u00e4t erh\u00f6ht und die eine eventuelle Heilung beschleunigt werden kann. Es verhindert zudem, dass sich Sehnen und B\u00e4nder \u00fcberdehnen.<\/li><li>Abschlie\u00dfend ist anzumerken, dass kurze\/verspannte Oberschenkelmuskeln einen erheblichen Einfluss auf die K\u00f6rperhaltung haben k\u00f6nnen. Eine verspannte Oberschenkelmuskulatur kann dazu f\u00fchren, dass sich das Becken nach hinten dreht, wodurch der nat\u00fcrliche Bogen des unteren R\u00fcckens abgeflacht wird. Dies wiederum kann Schmerzen beim Sitzen und Stehen hervorrufen. Das regelm\u00e4\u00dfige Dehnen der Oberschenkel und die Mobilisierung der H\u00fcfte verbessern nicht nur die allgemeine K\u00f6rperhaltung, sondern lindern auch Steifheit und Schmerzen im unteren R\u00fcckenbereich, die w\u00e4hrend und nach dem Training auftreten k\u00f6nnen.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed-vimeo wp-block-embed is-type-video is-provider-vimeo wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hamstring stretch\" src=\"https:\/\/player.vimeo.com\/video\/194312543?h=844a906d73&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>ANDERE \u00dcBUNGEN:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/de\/inverted-press\/\">TUTORIAL: INVERTED PRESS<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/evofitness.ch\/de\/lean-back-squat\/\">TUTORIAL: LEAN BACK SQUAT<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit einer tollen superfunktionalen \u00dcbung starten wir in den neuen Monat. In diesem Tutorial erkl\u00e4ren wir dir, wie du superfunktionelle&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Tutorial: Superfunktionelle Oberschenkeldehnung | EVO Fitness","_seopress_titles_desc":"Die superfunktionelle Oberschenkeldehnung ist eine tolle Alternative zur klassischen Variante. Verbessere deine Flexibilit\u00e4t und sportliche Leistung.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Oberschenkeldehnung","footnotes":""},"categories":[101],"tags":[1308,1309,1311,1322,1452,1686,1926,2083,2143,2164],"class_list":["post-57549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn","tag-fitness-2","tag-functional-training-2","tag-warm-up-2","tag-cool-down-2","tag-mobility-2","tag-flexibilitat-2","tag-beweglichkeit-2","tag-dehnung-2","tag-superfunktionell-2","tag-oberschenkel-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57549"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57548"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}