{"id":57223,"date":"2019-02-12T00:00:00","date_gmt":"2019-02-11T23:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/vier-funktionelle-uebungen-fuer-zwei\/"},"modified":"2019-02-12T00:00:00","modified_gmt":"2019-02-11T23:00:00","slug":"vier-funktionelle-uebungen-fuer-zwei","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/move\/vier-funktionelle-uebungen-fuer-zwei\/","title":{"rendered":"Vier funktionelle Herzklopf-\u00dcbungen f\u00fcr zwei"},"content":{"rendered":"<p style=\"text-align: justify\">Valentinstag steht vor der T\u00fcr und m\u00f6glicherweise hast du mit deiner besseren H\u00e4lfte geplant, etwas Zeit zu zweit zu verbringen. Ein Ausflug, ein romantisches Abendessen, oder einfach gemeinsam auf dem Sofa liegen. Wenn ihr stattdessen lieber k\u00f6rperlich aktiv werden m\u00f6chtet \u2013 und zwar nicht nur im Schlafzimmer \u2013 geht zusammen ins Fitnessstudio. <strong>Gemeinsam zu trainieren kann sich positiv auf eure Beziehung auswirken.<\/strong><\/p>\n<p style=\"text-align: justify\">Was sind Rosen und Schokolade gegen\u00fcber ein bisschen Konkurrenz, dem Erreichen gemeinsamer Ziele und einem herrlichen Endorphinrausch? Das f\u00fchrt nicht nur zu einem effektiven Workout, sondern auch zu einer gl\u00fccklicheren Beziehung und einem besseren Liebesleben.<\/p>\n<p style=\"text-align: justify\">Vereinfacht gesagt basiert funktionelles Training auf Bewegungen, f\u00fcr die wir von Natur aus geschaffen sind. Mit anderen Worten, zielgerichtete, geschickte und spielerische Bewegungen. Wir haben <strong>vier funktionelle \u00dcbungen<\/strong> zusammengestellt, die genau auf dieser Logik basieren und die du zusammen mit deinem Partner machen kannst. Sie werden eure Herzen zum Klopfen, euer Blut in Wallungen und eure Endorphine ins Rauschen bringen \u2013 und das kann euer Beziehung nur gut tun.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Ausfallschritte der Liebe<\/h2>\n<p style=\"text-align: justify\">Jeder m\u00f6chte seinen Liebsten oder seine Liebste gerne mit einem <a href=\"https:\/\/evofitness.ch\/de\/4-uebungen-po\/\">knackigen Po<\/a> beeindrucken. Mit dieser <strong>einfachen \u00dcbung f\u00fcr Oberschenkel und Ges\u00e4\u00dfmuskeln<\/strong> wird\u2019s m\u00f6glich. So geht\u2019s:<\/p>\n<ol>\n<li style=\"text-align: justify\">Stelle dich aufrecht hin: Deine F\u00fc\u00dfe stehen h\u00fcftbreit auseinander, dein Brustkorb ist ge\u00f6ffnet und dein Kinn gehoben.<\/li>\n<li style=\"text-align: justify\">Mache mit deinem rechten Bein einen Schritt nach vorne und sinke mit der H\u00fcfte nach unten, sodass dein rechtes Knie einen 90\u00b0 Winkel formt, beziehungsweise sich genau \u00fcber deinem Fu\u00df befindet. Halte dein Schienbein parallel zum Boden.<\/li>\n<li style=\"text-align: justify\">Dr\u00fccke dich mit dem rechten Fu\u00df wieder nach oben und gehe in die Ausgangsposition.<\/li>\n<li style=\"text-align: justify\">Wiederhole die Bewegung auf der linken Seite.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">S\u00fc\u00dfe Switch Kicks<\/h2>\n<p style=\"text-align: justify\">Was gibt es sch\u00f6neres als sich gegenseitig anzugucken? Ihr werdet es lieben, euch bei dieser \u00dcbung in die Augen zu schauen. Aber lasst euch von der ganzen Romantik nicht t\u00e4uschen \u2013 diese \u00dcbung hat es in sich. Holt eure Matte, es ist Zeit <strong>Trizeps, Oberschenkel und K\u00f6rpermitte zu definieren<\/strong>.<\/p>\n<ol>\n<li style=\"text-align: justify\">Setze dich auf den Boden. Beuge deine Knie, sodass deine F\u00fc\u00dfe flach auf dem Boden stehen und setze deine H\u00e4nde hinter dir flach auf dem Boden ab (deine Finger zeigen in Richtung deiner F\u00fc\u00dfe).<\/li>\n<li style=\"text-align: justify\">Hebe deine H\u00fcfte hoch; H\u00e4nde und F\u00fc\u00dfe bleiben dabei auf dem Boden.<\/li>\n<li style=\"text-align: justify\">Mache mit deinem linken Bein einen schnellen Tritt in die H\u00f6he, sofort gefolgt von deinem rechten. Die erste Wiederholung ist geschafft.<\/li>\n<li style=\"text-align: justify\">Wiederhole diese abwechselnden explosiven Tritte f\u00fcr 40 Sekunden.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Spr\u00fcnge des Gl\u00fccks<\/h2>\n<p style=\"text-align: justify\">Bei dieser Bewegung k\u00f6nnt Ihr euch gegenseitig anfeuern &#8211; <strong>Endorphinrausch garantiert<\/strong>. Stellt euch gegen\u00fcber und macht zum Beat eures Lieblingslieds abwechselnd Hockspr\u00fcnge. Bereit?<\/p>\n<ol>\n<li style=\"text-align: justify\">Stelle dich mit den F\u00fc\u00dfen h\u00fcftbreit auseinander gerade hin und beuge deine Knie leicht. Beuge deine Ellbogen im 90\u00b0 Winkel, sodass sich deine Unterarme im 90\u00b0 Winkel zum Boden befinden.<\/li>\n<li style=\"text-align: justify\">Beuge deine Knie und sinke in eine halbe Kniebeugen-Position.<\/li>\n<li style=\"text-align: justify\">Mache einen explosiven Sprung und ziehe dabei deine Knie so weit nach oben, dass deine Knie deine Unterarme ber\u00fchren.<\/li>\n<li style=\"text-align: justify\">Lande sanft auf deinen Zehen und wiederhole diese Bewegung f\u00fcr 30 Sekunden.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Herzspr\u00fcnge<\/h2>\n<p style=\"text-align: justify\">F\u00fcr diese \u00dcbung ben\u00f6tigst du ein Springseil. Sie l\u00e4sst nicht nur Kindheitserinnerungen wach werden, sondern <strong>verbrennt eine Menge Kalorien<\/strong> und trainiert den gesamten K\u00f6rper. Haltet ausreichend Abstand zwischen euch beiden, damit ihr euch mit dem Seil nicht in die Quere kommt \u2013 aber nicht weiter als das, am Valentinstag wollt ihr euch ja schlie\u00dflich tief in die Augen schauen.<\/p>\n<ol>\n<li style=\"text-align: justify\">Fasse das Springseil. Das Seil liegt hinter dir und deine Ellbogen liegen an deinem K\u00f6rper an.<\/li>\n<li style=\"text-align: justify\">Mache mit gehobenen Fersen sanfte Spr\u00fcnge \u00fcber das Seil, welches du aus den Handgelenken heraus \u00fcber deinen Kopf bringst. Ein Sprung entspricht einer Wiederholung.<\/li>\n<li style=\"text-align: justify\">Springe eine Minute lang ohne Pause. Mache 5 S\u00e4tze.<\/li>\n<\/ol>\n<p style=\"text-align: justify\"><strong>Die Idee, zusammen zu trainieren, findet ihr toll, aber ich m\u00f6chtet euer Workout selber gestalten? <a href=\"https:\/\/evofitness.ch\/de\/\">Besucht EVO<\/a>, probiert unseren Fitness Playground und verbindet K\u00f6rper und Geist auf eine nat\u00fcrliche, spielerische und funktionelle Art und Weise. <\/strong><\/p>\n<p><strong>Vergiss nicht, deine Meinung mit uns auf <a href=\"https:\/\/facebook.com\/EvoFitnessSwiss\/\">Facebook<\/a> oder <a href=\"https:\/\/www.instagram.com\/evofitness_official\/\">Instagram<\/a> zu teilen!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valentinstag steht vor der T\u00fcr und m\u00f6glicherweise hast du mit deiner besseren H\u00e4lfte geplant, etwas Zeit zu zweit zu verbringen&#8230;.<\/p>\n","protected":false},"author":17,"featured_media":57224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"4 funktionelle \u00dcbungen f\u00fcr Zwei | EVO Fitness","_seopress_titles_desc":"Valentinstag steht vor der T\u00fcr. Hier sind vier funktionelle \u00dcbungen f\u00fcr dich und deine bessere H\u00e4lfte, die eure Herzen h\u00f6herschlagen lassen.","_seopress_robots_index":"","_seopress_analysis_target_kw":"valentinstag","footnotes":""},"categories":[102],"tags":[130,1309,1327,1343,1721,1959,1960],"class_list":["post-57223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-move","tag-funktionelles-training","tag-functional-training-2","tag-tutorial-2","tag-bodyweight-2","tag-korpergewicht-2","tag-ubungen-fur-zwei","tag-valentinstag-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57223"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57224"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}