{"id":57060,"date":"2018-09-24T00:00:00","date_gmt":"2018-09-23T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/pegboard-training-2\/"},"modified":"2018-09-24T00:00:00","modified_gmt":"2018-09-23T22:00:00","slug":"pegboard-training-2","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/discover\/pegboard-training-2\/","title":{"rendered":"Was ist Pegboard? Was sind die Vorteile von Pegboard Training?"},"content":{"rendered":"<p style=\"text-align: justify\">In einer Studie, welche die Muskelaktivierung bei verschiedenen Klimmzug-Variationen, Seilklettern, Muscle-ups und dem Pegboard vergleicht, zeigte letzteres <strong>die besten Ergebnisse im Bezug auf Muskelwachstum<\/strong>. Klettern am Pegboard ist eine einfache aber effektive Erg\u00e4nzung zum Kraft- und Oberk\u00f6rpertraining. Die funktionellen \u00dcbungen verbessern die Leistung von z.B. Gewichthebern im Rahmen eines angemessenen athletischen Trainings.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Welche Muskeln werden am Pegboard trainiert?<\/h2>\n<p style=\"text-align: justify\">Das Pegboard wurde urspr\u00fcnglich f\u00fcr Kletterer der verschiedensten Kletterdisziplinen entwickelt. Es beansprucht also genau die Muskeln, die beim Klettern aktiviert werden:<\/p>\n<ul>\n<li style=\"text-align: justify\">Gro\u00dfer R\u00fcckenmuskel<\/li>\n<li style=\"text-align: justify\">Schultermuskeln<\/li>\n<li style=\"text-align: justify\">Bizeps<\/li>\n<li style=\"text-align: justify\">Unterarmmuskeln<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Das Pegboard <strong>stimuliert vor allem die kleineren Muskeln<\/strong>, die durch gew\u00f6hnliches Hanteltraining oder Eigengewicht\u00fcbungen schwerer zu erreichen sind, wie zum Beispiel der Teres Major, der unterhalb des Schulterblattes liegt. Dieser ist ist f\u00fcr die interne Rotation des Armes, sowie f\u00fcr die Zur\u00fcckf\u00fchrung des Armes zum K\u00f6rper, nachdem er seitlich ausgestreckt wurde, verantwortlich.<\/p>\n<p style=\"text-align: justify\">Bei vielen Athleten ist <strong>der Teres Major unterentwickelt<\/strong>, da sie oft weder die Rotation, noch die Bewegung des Armes zum K\u00f6rper hin mit Gewichten trainieren. Probleme an der Schulter sind daher weit verbreitet. Regelm\u00e4\u00dfiges Pegboardtraining kann dem entgegenwirken und Verletzungen vorbeugen.<\/p>\n<p style=\"text-align: justify\">Ein weiteres Beispiel: <strong>Der Brachialis<\/strong>, etwa oberhalb des Ellenbogens gelegen, der genau wie der Bizeps f\u00fcr die Beugung des Unterarms verantwortlich ist. Im Gegensatz zu dem weit bekannteren Bizeps, kann der Brachialis die Beugung des Unterarms selbst dann hervorrufen, wenn die Handfl\u00e4che nach unten zeigt.<\/p>\n<p style=\"text-align: justify\">Genau dies ist eine typische Positionierung der H\u00e4nde auf der Langhantel beim Gewichtheben. Das speziell den Brachialis trainierende Pegboard bewirkt eine Steigerung der Leistungsf\u00e4higkeit in dieser \u00dcbung. Im Allgemeinen handelt es sich beim Pegboardtraining um <strong>eine sehr intensive k\u00f6rperliche Bet\u00e4tigung f\u00fcr den gesamten Oberk\u00f6rper<\/strong>. In einer Studie, die die Muskelaktivierung bei verschiedenen Klimmzug-Variationen, Seilklettern, Muscle-ups und dem Pegboard vergleicht, zeigte letzteres die besten Ergebnisse f\u00fcr das Wachstum von Latissimus, Bizeps und Brustmuskeln.<\/p>\n<p style=\"text-align: justify\">Mehreren Statistiken zufolge, <strong>entspricht ein Pegboard-Aufstieg 26 Klimmz\u00fcgen<\/strong> im Hinblick auf Intensit\u00e4t (Muskelaktivierung und Herzschlag).<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Ein besserer Athlet dank Pegboard:<\/h2>\n<p style=\"text-align: justify\">Das Pegboard dient jedoch nicht nur dem Muskelaufbau. Kletterer und Calisthenics Athleten nutzen das Training am Pegboard, um ihre <strong>Kraftausdauer zu verbessern<\/strong>. Der Athlet \u00fcbt, den Stab f\u00fcr mehrere Sekunden mit nur einer Hand festzuhalten. Je nach Kompetenzen kann der gesamte Kletterprozess 30 bis 60 Sekunden dauern. Das ist ganz sch\u00f6n anstrengend!<\/p>\n<p style=\"text-align: justify\">Das Pegboard ist zudem <strong>eine ausgezeichnete Stabilit\u00e4ts\u00fcbung.<\/strong> Viele kleine und signifikante Muskelgruppen sind so aufeinander abgestimmt, um in einer harmonischen Art und Weise die K\u00f6rperspannung zu aufrechtzuerhalten. Dies schafft die perfekte Grundlage f\u00fcr effektives Training (Schmetterlings-Klimmz\u00fcge, Muscle-ups usw.) und f\u00f6rdert die Gesundheit der Gelenke. Zus\u00e4tzlich verbessert der Athlet nicht nur die Koordination von H\u00e4nden und Augen, sondern auch die mentale St\u00e4rke.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Tipps f\u00fcr die korrekte Ausf\u00fchrung<\/h2>\n<ul>\n<li style=\"text-align: justify\">Halte <strong>deinen K\u00f6rper so nah wie m\u00f6glich<\/strong> am Brett.<\/li>\n<li style=\"text-align: justify\">Stelle sicher, dass du immer <strong>eine Halte- und eine Wechselseite<\/strong> hast. Wenn du zum Beispiel den Stab auf der linken Seite wechseln m\u00f6chtest, verlagere dein Gewicht auf die rechte Seite.<\/li>\n<li style=\"text-align: justify\">Deine <strong>Brust sollte immer auf H\u00f6he des Stabs auf der Halteseite<\/strong> sein, nie zwischen den beiden St\u00e4ben oder tiefer als deine unterste Hand.<\/li>\n<li style=\"text-align: justify\"><strong>Ziehe den Stab immer horizontal<\/strong> aus einem Loch heraus, nicht in einer herabsinkenden Bewegung (ansonsten bleibst du im Loch stecken und verlierst dadurch wertvolle Zeit).<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Das Pegboard eignet sich nicht nur zum Hoch- und Runterklettern. Man kann daran auch verschiedene <strong>Klimmzug-Variationen<\/strong> aus\u00fcben. Befestige die St\u00e4be an verschiedenen Positionen auf dem Brett und trainiere enge, weite oder verschobene Klimmz\u00fcge. Wer nach einer neuen Bauchmuskel\u00fcbung sucht, kann verschiedene Beinhebe-Variationen am Pegboard ausprobieren.<\/p>\n<p><strong>Vergiss nicht, deine Meinung mit uns auf <a href=\"https:\/\/facebook.com\/EvoFitnessSwiss\/\">Facebook<\/a> oder <a href=\"https:\/\/www.instagram.com\/evofitness_official\/\">Instagram<\/a> zu teilen!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einer Studie, welche die Muskelaktivierung bei verschiedenen Klimmzug-Variationen, Seilklettern, Muscle-ups und dem Pegboard vergleicht, zeigte letzteres die besten Ergebnisse&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[99],"tags":[1343,1659,1721,1850,1317],"class_list":["post-57060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-discover","tag-bodyweight-2","tag-ubung-2","tag-korpergewicht-2","tag-pegboard-2","tag-training-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57060"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57059"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}