{"id":57011,"date":"2018-08-17T00:00:00","date_gmt":"2018-08-16T22:00:00","guid":{"rendered":"https:\/\/evofitness.ch\/blog\/uncategorized\/animal-athletics-2\/"},"modified":"2018-08-17T00:00:00","modified_gmt":"2018-08-16T22:00:00","slug":"animal-athletics-2","status":"publish","type":"post","link":"https:\/\/evofitness.ch\/de\/blog\/move\/animal-athletics-2\/","title":{"rendered":"Wir stellen vor: Animal Athletics \u2013 Eigengewichtstraining am Boden"},"content":{"rendered":"<p style=\"text-align: justify\">Bei den meisten Sportarten und Trainingsmethoden sind die Athleten und Sportler\/-innen in einer aufrechten Position. \u00dcbungen, die am Boden ausgef\u00fchrt werden und auf Bodenkontakt basieren, sind eine gute Abwechslung f\u00fcr jede Trainingsroutine. Es handelt sich um \u00dcbungen und Bewegungen, die nicht im Stehen ausgef\u00fchrt werden, sondern zum Beispiel horizontal oder krabbelnd \u2013 am Boden eben.<\/p>\n<p style=\"text-align: justify\">Diese Art des Trainings basiert auf fr\u00fchkindlichen Bewegungsmustern und Tieren nachempfundenen Bewegungen. Daher auch der Name: Animal Athletics. Stell dir vor, wie sich zum Beispiel Krebse, Affen oder Eidechsen fortbewegen. All diese Bewegungen werden bei Animal Athletics nachgeahmt.<\/p>\n<p style=\"text-align: justify\"><strong>Dieses Eigengewichtstraining f\u00f6rdert Bewegungsintelligenz, Kontrolle und Dynamik.<\/strong> Das Wiedererlernen vergessener Bewegungsmuster, die f\u00fcr Kinder ganz selbstverst\u00e4ndlich sind, ist ein zentraler Aspekt dieses Ansatzes. Funktionelle Bewegung basiert auf Propriozeptoren, welche die Wahrnehmung der Stellung und Bewegung des K\u00f6rpers im Raum gew\u00e4hrleisten.<\/p>\n<p style=\"text-align: justify\">In Bruchteilen einer Sekunde wird die Information \u00fcber die Stellung und Position des K\u00f6rpers im Raum an das R\u00fcckenmark gesendet und der K\u00f6rper reagiert. Dabei werden Rezeptoren in denjenigen Bewegungen und Haltungen, f\u00fcr die sie gemacht sind, trainiert. Beim Menschen ist dies die aufrechte Haltung. In der Fachterminologie nennt man dies \u201apropriozeptive Integrit\u00e4t\u2018.<\/p>\n<p style=\"text-align: justify\"><strong>Diese nat\u00fcrliche Entwicklung folgt einer mehr oder weniger chronologischen Sequenz (neuromuskoloskeletale Entwicklungssequenz):<\/strong><\/p>\n<ul style=\"text-align: justify\">\n<li>Auf dem Bauch liegend den Kopf heben, 1-2 Monate<\/li>\n<li>Komplette Kontrolle \u00fcber den Kopf, 4 Monate<\/li>\n<li>Auf dem Bauch liegend werden die Unterarme zur Unterst\u00fctzung benutzt, 6 Monate<\/li>\n<li>Auf dem Bauch liegend, der ganze Arm wird benutzt um den Oberk\u00f6rper aufzurichten, 6 Monate<\/li>\n<li>In eine seitliche Position rollen (posturaler Reflex), 1-2 Monate<\/li>\n<li>Aus der seitlichen Position auf den Bauch rollen, 4-5 Monate<\/li>\n<li>Vom Bauch auf den R\u00fccken rollen<\/li>\n<li>Vom R\u00fccken auf den Bauch rollen, 6-8 Monate<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Anders als viele andere S\u00e4ugetiere braucht der Mensch ungef\u00e4hr 18 Monate, bis er laufen kann. Zuerst handelt es sich dabei um bodennahe Bewegungen (rollen, kriechen, krabbeln), die langsam zu mehr oder weniger kontrollierten aufrechten Bewegungen werden. Dabei reift das Nerven-, Muskel-und Skelettsystem des K\u00f6rpers heran.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Was genau ist Animal Athletics und warum solltest du es zu einem Teil deiner Trainingsroutine machen?<\/h2>\n<p style=\"text-align: justify\">\u00dcbungen auf dem Boden auszuf\u00fchren (wie zum Beispiel bei Animal Athletics) bedeutet dorthin zur\u00fcckzukehren, wo wir als Kinder alle grundlegenden Bewegungsmuster gelernt haben. Indem wir auf einem niedrigeren Bewegungslevel trainieren, verbessern wir die Qualit\u00e4t unserer Bewegungen auf dem h\u00f6heren Level (die aufrechte Haltung). Stell dir einen erfahrenen Pianisten vor, der kontinuierlich Finger\u00fcbungen auf dem Klavier durchf\u00fchrt, um seine herausfordernden Symphonien besser spielen zu k\u00f6nnen. Diese schwierigen Symphonien stehen f\u00fcr die komplexen Bewegungsmuster des menschlichen K\u00f6rpers.<\/p>\n<p style=\"text-align: justify\">Unsere Bewegung wird von \u00e4u\u00dferen Einfl\u00fcssen, Impulsen und Gef\u00fchlen bestimmt, unter anderem <strong>von k\u00f6rperlichen und biologischen Faktoren<\/strong>. K\u00f6rperliche Faktoren sind solche, die unseren K\u00f6rper direkt betreffen, wie seine eigene Masse (K\u00f6rpergewicht), der entsprechende Impuls (umgangssprachlich \u201eSchwung des K\u00f6rpers\u201c), die Schwerkraft und die Bodenreaktionskraft (die Kraft, die zwischen Boden und K\u00f6rper wirkt).<\/p>\n<p style=\"text-align: justify\">Die Schwerkraft zieht unseren K\u00f6rper zum Boden und \u00fcbt einen nach unten gerichteten direkten Druck auf den K\u00f6rper aus. Der K\u00f6rper muss der Schwerkraft entgegenwirken. Um zu verhindern hinzufallen, reagiert die gesamte Muskulatur in einer Art Kettenreaktion. Dadurch wird gezielte Fortbewegung erm\u00f6glicht. Je nachdem, ob wir uns in aufrechter Position oder am Boden befinden, m\u00fcssen unsere vier Extremit\u00e4ten und der Schwung unseres K\u00f6rpers allerdings anders reagieren, um nicht hinzufallen.<\/p>\n<p style=\"text-align: justify\">Training auf dem Boden basiert genau auf dieser unterschiedlichen Reaktion unseres K\u00f6rpers. Nicht nur die Reaktion des K\u00f6rpers auf die Schwerkraft, sondern auch andere Aspekte ver\u00e4ndern sich je nach Position, wie zum Beispiel der Winkel unserer Gelenke, das Zusammenspiel der Muskeln und einige physiologische Komponenten wie die Atmung und Durchblutung.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Vorteile von Training am Boden:<\/h2>\n<ul>\n<li style=\"text-align: justify\">Maximale Aktivierung der Rezeptoren<\/li>\n<li style=\"text-align: justify\">Verbesserte Beweglichkeit<\/li>\n<li style=\"text-align: justify\">Bewusster Umgang mit der Schwerkraft<\/li>\n<li style=\"text-align: justify\">Geringere Belastung der Wirbels\u00e4ule<\/li>\n<li style=\"text-align: justify\">Verbesserte Durchblutung<\/li>\n<li style=\"text-align: justify\">Verbesserte Verdauung<\/li>\n<li style=\"text-align: justify\">Verbesserte Atmung<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><em>BardoTschapke, Evo Le Flair D\u00fcsseldorf<\/em><br \/>\nInstagram: <a href=\"https:\/\/www.instagram.com\/healthcoachbardo\/\">healthcoachbardo<\/a><br \/>\nFacebook: <a href=\"https:\/\/www.facebook.com\/healthcoachbardo\/\">Health Coach Bardo<\/a><\/p>\n<p><strong>Vergiss nicht, deine Meinung mit uns auf <a href=\"https:\/\/facebook.com\/EvoFitnessSwiss\/\">Facebook<\/a> oder <a href=\"https:\/\/www.instagram.com\/evofitness_official\/\">Instagram<\/a> zu teilen!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei den meisten Sportarten und Trainingsmethoden sind die Athleten und Sportler\/-innen in einer aufrechten Position. \u00dcbungen, die am Boden ausgef\u00fchrt&#8230;<\/p>\n","protected":false},"author":17,"featured_media":57010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[102],"tags":[130,1343,1373,1721,1808],"class_list":["post-57011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-move","tag-funktionelles-training","tag-bodyweight-2","tag-animal-athletics-2","tag-korpergewicht-2","tag-expertenrat-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/comments?post=57011"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/posts\/57011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media\/57010"}],"wp:attachment":[{"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/media?parent=57011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/categories?post=57011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.ch\/de\/wp-json\/wp\/v2\/tags?post=57011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}